{"id":10999,"date":"2013-06-06T20:12:53","date_gmt":"2013-06-07T00:12:53","guid":{"rendered":"http:\/\/elizabethmaymp.ca?p=10999"},"modified":"2013-11-13T20:15:31","modified_gmt":"2013-11-14T01:15:31","slug":"expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/","title":{"rendered":"Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15)"},"content":{"rendered":"<p><strong>Elizabeth May :<\/strong> Monsieur le Pr\u00e9sident, je d\u00e9plore profond\u00e9ment le fait que le gouvernement ait recours \u00e0 l&#8217;attribution de temps pour cette mesure l\u00e9gislative. Je partage enti\u00e8rement le point de vue de ma coll\u00e8gue d&#8217;Halifax. Il est essentiel de prot\u00e9ger ad\u00e9quatement l&#8217;\u00eele de Sable. Nous voulons tous que soit cr\u00e9\u00e9 le parc national de l&#8217;\u00eele-de-Sable, mais cela ne doit pas se faire au d\u00e9triment de l&#8217;int\u00e9grit\u00e9 de notre r\u00e9seau de parcs nationaux, en accordant \u00e0 l&#8217;Office Canada-Nouvelle-\u00c9cosse des hydrocarbures extrac\u00f4tiers le droit de prendre des r\u00e8glements qui auront une incidence sur un parc national. C&#8217;est du jamais vu.<\/p>\n<p>Contrairement \u00e0 ce que le ministre vient tout juste d&#8217;affirmer, des groupes environnementaux de la Nouvelle-\u00c9cosse ont communiqu\u00e9 avec moi afin de me faire part de leurs profondes inqui\u00e9tudes. Ils ne veulent pas que le projet de loi soit adopt\u00e9 dans sa forme actuelle et ils souhaitent prot\u00e9ger l&#8217;int\u00e9grit\u00e9 du r\u00e9seau des parcs nationaux.<\/p>\n<p>Cette mesure l\u00e9gislative doit faire l&#8217;objet d&#8217;un d\u00e9bat approfondi. \u00c9courter le d\u00e9bat sur ce projet de loi et chercher \u00e0 le faire adopter \u00e0 toute vitesse, \u00e0 la derni\u00e8re minute, ne constitue un affront non seulement \u00e0 la d\u00e9mocratie, mais aussi \u00e0 l&#8217;int\u00e9grit\u00e9 du r\u00e9seau des parcs nationaux du Canada.<\/p>\n<p><strong>L&#8217;hon. Peter Kent :<\/strong> Monsieur le Pr\u00e9sident, j&#8217;aimerais remercier encore une fois ma coll\u00e8gue pour ses observations.<\/p>\n<p>J&#8217;aimerais aussi lui rappeler, encore une fois, que pendant l&#8217;\u00e9laboration de ce projet de loi, donc pendant les consultations publiques, y compris celles auxquelles ont particip\u00e9 des ONG environnementales et des Premi\u00e8res Nations de la Nouvelle-\u00c9cosse, il s&#8217;est cr\u00e9\u00e9 un vaste consensus \u00e0 propos des conditions, des dispositions et des r\u00e8glements qui encadreraient la cr\u00e9ation de ce nouveau parc national.<\/p>\n<p>Le projet de loi a \u00e9t\u00e9 pr\u00e9sent\u00e9 \u00e0 l&#8217;assembl\u00e9e l\u00e9gislative de la Nouvelle-\u00c9cosse le 24 avril. Il a \u00e9t\u00e9 lu pour la deuxi\u00e8me fois le 25 avril et pour la troisi\u00e8me fois le 6 mai, et il a re\u00e7u la sanction royale le 10 mai. Pendant le d\u00e9bat, le leader parlementaire du Parti lib\u00e9ral a d\u00e9clar\u00e9 ceci :<\/p>\n<p style=\"padding-left: 30px;\"><em>[&#8230;] nous avons h\u00e2te que le projet de loi soit renvoy\u00e9 au comit\u00e9 charg\u00e9 d&#8217;examiner les modifications l\u00e9gislatives et que son \u00e9tude se poursuive \u00e0 la Chambre [&#8230;] en collaboration avec le gouvernement f\u00e9d\u00e9ral, le parc de l&#8217;\u00cele-de-Sable deviendra bient\u00f4t officiellement le 43e parc national du Canada.<\/em><\/p>\n<p>Nous avons re\u00e7u des commentaires semblables de la part des progressistes-conservateurs et du parti au pouvoir, le NPD. Ils nous ont signal\u00e9 leur appui et ont dit esp\u00e9rer que nous pourrions promulguer cette loi cette ann\u00e9e.<\/p>\n<p>Pour ce qui est de l&#8217;entente avec l&#8217;industrie p\u00e9troli\u00e8re et gazi\u00e8re, elle viendra en fait prot\u00e9ger l&#8217;\u00eele. Sans l&#8217;initiative et la collaboration du secteur p\u00e9trolier et gazier, nous ne serions pas ici aujourd&#8217;hui, \u00e0 envisager de faire de l&#8217;\u00eele de Sable un parc national prot\u00e9g\u00e9. Ces entreprises ont accept\u00e9 de renoncer aux baux qu&#8217;elles d\u00e9tenaient depuis quelques ann\u00e9es et qui auraient pu leur rapporter beaucoup.<\/p>\n<p>Selon les termes de l&#8217;entente, le territoire du parc couvrira une zone tampon d&#8217;un mille marin au-del\u00e0 des plages \u00e0 mar\u00e9e basse, de mani\u00e8re \u00e0 emp\u00eacher toute activit\u00e9 au large. La grande experte de l&#8217;\u00eele de Sable, Mme Zoe Lucas, a affirm\u00e9 que les rares activit\u00e9s qui ont eu lieu par le pass\u00e9 et qui seront permises \u00e0 l&#8217;avenir ont une incidence tr\u00e8s faible sur l&#8217;environnement, et qu&#8217;elles ne devraient avoir aucun effet sur l&#8217;habitat ou sur les esp\u00e8ces de ce milieu.<\/p>","protected":false},"excerpt":{"rendered":"<p>Elizabeth May : Monsieur le Pr\u00e9sident, je d\u00e9plore profond\u00e9ment le fait que le gouvernement ait recours \u00e0 l&#8217;attribution de temps pour cette mesure l\u00e9gislative. Je partage enti\u00e8rement le&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-10999","post","type-post","status-publish","format-standard","hentry","category-debate"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15) | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15) | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Elizabeth May : Monsieur le Pr\u00e9sident, je d\u00e9plore profond\u00e9ment le fait que le gouvernement ait recours \u00e0 l&#8217;attribution de temps pour cette mesure l\u00e9gislative. Je partage enti\u00e8rement le&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-07T00:12:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-11-14T01:15:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Craig Cantin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Craig Cantin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\\\/\"},\"author\":{\"name\":\"Craig Cantin\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\"},\"headline\":\"Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15)\",\"datePublished\":\"2013-06-07T00:12:53+00:00\",\"dateModified\":\"2013-11-14T01:15:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\\\/\"},\"wordCount\":1146,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"articleSection\":[\"D\u00e9bat\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\\\/\",\"name\":\"Expansion and Conservation of Canada\u2019s National Parks Act (Bill S-15)Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15) | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2013-06-07T00:12:53+00:00\",\"dateModified\":\"2013-11-14T01:15:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expansion and Conservation of Canada\u2019s National Parks Act (Bill S-15)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\",\"name\":\"Craig Cantin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"caption\":\"Craig Cantin\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/craig-c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15) | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/","og_locale":"en_US","og_type":"article","og_title":"Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15) | Elizabeth May","og_description":"Elizabeth May : Monsieur le Pr\u00e9sident, je d\u00e9plore profond\u00e9ment le fait que le gouvernement ait recours \u00e0 l&#8217;attribution de temps pour cette mesure l\u00e9gislative. Je partage enti\u00e8rement le&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2013-06-07T00:12:53+00:00","article_modified_time":"2013-11-14T01:15:31+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Craig Cantin","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Craig Cantin","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/"},"author":{"name":"Craig Cantin","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f"},"headline":"Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15)","datePublished":"2013-06-07T00:12:53+00:00","dateModified":"2013-11-14T01:15:31+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/"},"wordCount":1146,"commentCount":0,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"articleSection":["D\u00e9bat"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/","url":"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/","name":"Expansion and Conservation of Canada\u2019s National Parks Act (Bill S-15)Loi sur le d\u00e9veloppement et la conservation des parcs nationaux du Canada (Projet de loi S-15) | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2013-06-07T00:12:53+00:00","dateModified":"2013-11-14T01:15:31+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/expansion-and-conservation-of-canadas-national-parks-act-bill-s-15-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Expansion and Conservation of Canada\u2019s National Parks Act (Bill S-15)"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f","name":"Craig Cantin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","caption":"Craig Cantin"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/craig-c\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/10999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=10999"}],"version-history":[{"count":1,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/10999\/revisions"}],"predecessor-version":[{"id":11000,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/10999\/revisions\/11000"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=10999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=10999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=10999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}