{"id":11541,"date":"2014-02-11T16:48:32","date_gmt":"2014-02-11T21:48:32","guid":{"rendered":"http:\/\/elizabethmaymp.ca?p=11541"},"modified":"2014-02-11T18:41:38","modified_gmt":"2014-02-11T23:41:38","slug":"harpers-olympic-budget-falls-well-short-of-the-podium","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/","title":{"rendered":"Le budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium"},"content":{"rendered":"<p>Elizabeth May, chef du Parti Vert du Canada, a \u00e9reint\u00e9 le budget 2014 de Stephen Harper comme \u00e9tant un ressassement de mesures m\u00e9diocres et de messages d\u00e9suets.<\/p>\n<p>\u00ab En commen\u00e7ant par les points positifs, il faut saluer d\u2019une m\u00e9daille d&#8217;or l\u2019instauration tant attendue de la\u00ab loi de Lindsey \u00bb \u2013 la banque de donn\u00e9es d&#8217;ADN \u00e0 l\u2019intention des personnes disparues \u2013; l&#8217;octroi aux jeunes de pr\u00eats, sur le mod\u00e8le de pr\u00eats aux \u00e9tudiants, pour les aider \u00e0 financer des apprentissages; de nouveaux fonds pour soutenir les programmes de stages, et de l&#8217;argent pour aider Parcs Canada aux prises avec sa propre infrastructure en d\u00e9combres \u00bb, a not\u00e9 Mme May, d\u00e9put\u00e9e de Saanich-Gulf Islands.<\/p>\n<p>Le Parti Vert note cependant l\u2019absence totale au budget de la moindre r\u00e9f\u00e9rence \u00e0 la crise urgente du besoin d\u2019investissements et d\u2019une r\u00e9glementation plus stricte dans le transport ferroviaire de marchandises, ni aucune r\u00e9f\u00e9rence \u00e0 la crise imminente du transport par rail de voyageurs partout au Canada.<\/p>\n<p>Le chef adjoint du Parti vert, Bruce Hyer, d\u00e9put\u00e9 de Thunder Bay-Superior-Nord, a d\u00e9clar\u00e9: \u00ab Ce budget continue \u00e0 surtaxer les petites entreprises et les familles, tandis qu\u2019il sous-taxe largement les grandes entreprises comme les grandes banques et les compagnies p\u00e9troli\u00e8res. Il s\u2019agit d\u2019un programme d\u00e9lib\u00e9r\u00e9 visant \u00e0 faire dispara\u00eetre les services dont les Canadiennes et les Canadiens ont besoin, en r\u00e9duisant l&#8217;imp\u00f4t factur\u00e9 aux grandes soci\u00e9t\u00e9s \u00e0 la moiti\u00e9 du taux en vigueur aux \u00c9tats-Unis, et ce sans m\u00eame exiger que ces entreprises investissent chez nous ou y cr\u00e9ent des emplois. \u00bb<\/p>\n<p>Le Parti Vert note que le gouvernement Harper a, comme beaucoup le craignaient, d\u00e9cid\u00e9 de s\u2019en prendre aux organismes de bienfaisance, et notamment aux groupes de d\u00e9fense de l\u2019environnement qui, de l&#8217;avis des Conservateurs, \u00ab ne fonctionnent pas de la mani\u00e8re pr\u00e9vue \u00bb. Cette nouvelle orientation donn\u00e9e aux enqu\u00eates de l&#8217;ARC a \u00e9t\u00e9 dissimul\u00e9e \u00e0 la page 259, loin du chapitre principal que le budget consacre aux organismes de bienfaisance, aux pages 212-215.<\/p>\n<p>\u00ab Ce qui est vraiment irritant dans le budget 2014 de n\u2019importe quel gouvernement moderne, c&#8217;est qu\u2019il n\u2019y a qu\u2019au Canada que la menace de la crise climatique n&#8217;est jamais mentionn\u00e9e. De fa\u00e7on paradoxale, on voit beaucoup d\u2019argent nouveau \u2013 environ 300 millions de dollars sur 5 ans \u2013 \u00eatre attribu\u00e9 pour faire face aux inondations, aux s\u00e9cheresses, aux incendies et \u00e0 d\u2019autres \u00e9v\u00e9nements m\u00e9t\u00e9orologiques extr\u00eames, qui vont augmenter en raison des changements climatiques \u00bb, a d\u00e9clar\u00e9 Mme May. \u00ab Pendant ce temps, on voit s\u2019acc\u00e9l\u00e9rer une mont\u00e9e de l&#8217;effet de serre \u00e0 cause de la croissance incontr\u00f4l\u00e9e de la production de combustibles fossiles : suppression des droits de douane sur les \u00e9quipements li\u00e9s au forage off-shore, hausse des m\u00e9canismes de r\u00e9ponse aux d\u00e9versements de p\u00e9trole, et un d\u00e9veloppement des ol\u00e9oducs, dont le budget semble pr\u00e9- approuver le projet \u00c9nergie Est en vue d\u2019accro\u00eetre l&#8217;exportation de bitume non trait\u00e9. \u00bb<\/p>\n<p>(Voir note ci-jointe pour la r\u00e9partition du chiffre de 300 M$)<\/p>\n<p>\u00abDans l&#8217;ensemble, la principale caract\u00e9ristique environnementale de ce budget est la jolie photo en page couverture de cyclistes profitant de nos spectaculaires raisons sauvages \u00bb, a conclu Mme May.<\/p>\n<hr \/>\n<p><strong>Ajout au communiqu\u00e9 de presse :<\/strong><\/p>\n<ul>\n<li>Le Parti vert souligne que, malgr\u00e9 le financement des mesures suivantes li\u00e9es au climat, le budget ne mentionne pas que les changements climatiques sont d\u00e9j\u00e0 \u00e0 l&#8217;origine de lourdes pertes pour l&#8217;\u00e9conomie canadienne :\u2019;<\/li>\n<li>Report d&#8217;imp\u00f4t pour les agriculteurs qui doivent vendre du b\u00e9tail d&#8217;\u00e9levage en raison de \u00ab conditions extr\u00eames de s\u00e9cheresse ou d\u2019exc\u00e8s d&#8217;humidit\u00e9 \u00bb (p. 149) ;<\/li>\n<li>Programme national d&#8217;att\u00e9nuation des catastrophes (200 millions $ sur 5 ans, p. 231) ;<\/li>\n<li>Gestion des urgences dans les r\u00e9serves pour aider les Premi\u00e8res Nations face \u00e0 des inondations et des incendies (40 millions $ sur 5 ans, p 231) ;<\/li>\n<li>Recherche d&#8217;une approche nationale en mati\u00e8re d\u2019assurance contre les inondations pour les propri\u00e9taires de maison (p. 232) ;<\/li>\n<li>Investir dans l&#8217;entretien des ports pour petits bateaux, qui, tout en n&#8217;\u00e9tant pas mentionn\u00e9s dans le budget, ont un besoin croissant d\u2019investissements en r\u00e9parations dues \u00e0 l&#8217;\u00e9l\u00e9vation du niveau de la mer et des vagues de temp\u00eate (40 millions $ sur deux ans, p. 167).<\/li>\n<\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Elizabeth May, chef du Parti Vert du Canada, a \u00e9reint\u00e9 le budget 2014 de Stephen Harper comme \u00e9tant un ressassement de mesures m\u00e9diocres et de messages d\u00e9suets. \u00ab&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[90],"tags":[],"class_list":["post-11541","post","type-post","status-publish","format-standard","hentry","category-press-releases"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Elizabeth May, chef du Parti Vert du Canada, a \u00e9reint\u00e9 le budget 2014 de Stephen Harper comme \u00e9tant un ressassement de mesures m\u00e9diocres et de messages d\u00e9suets. \u00ab&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-11T21:48:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-11T23:41:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Craig Cantin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Craig Cantin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/harpers-olympic-budget-falls-well-short-of-the-podium\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/harpers-olympic-budget-falls-well-short-of-the-podium\\\/\"},\"author\":{\"name\":\"Craig Cantin\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\"},\"headline\":\"Le budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium\",\"datePublished\":\"2014-02-11T21:48:32+00:00\",\"dateModified\":\"2014-02-11T23:41:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/harpers-olympic-budget-falls-well-short-of-the-podium\\\/\"},\"wordCount\":1283,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"articleSection\":[\"Communiqu\u00e9s\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/harpers-olympic-budget-falls-well-short-of-the-podium\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/harpers-olympic-budget-falls-well-short-of-the-podium\\\/\",\"name\":\"Harper\u2019s Olympic Budget falls well short of the podiumLe budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2014-02-11T21:48:32+00:00\",\"dateModified\":\"2014-02-11T23:41:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/harpers-olympic-budget-falls-well-short-of-the-podium\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/harpers-olympic-budget-falls-well-short-of-the-podium\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/harpers-olympic-budget-falls-well-short-of-the-podium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Harper\u2019s Olympic Budget falls well short of the podium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\",\"name\":\"Craig Cantin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"caption\":\"Craig Cantin\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/craig-c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/","og_locale":"en_US","og_type":"article","og_title":"Le budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium | Elizabeth May","og_description":"Elizabeth May, chef du Parti Vert du Canada, a \u00e9reint\u00e9 le budget 2014 de Stephen Harper comme \u00e9tant un ressassement de mesures m\u00e9diocres et de messages d\u00e9suets. \u00ab&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2014-02-11T21:48:32+00:00","article_modified_time":"2014-02-11T23:41:38+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Craig Cantin","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Craig Cantin","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/harpers-olympic-budget-falls-well-short-of-the-podium\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/harpers-olympic-budget-falls-well-short-of-the-podium\/"},"author":{"name":"Craig Cantin","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f"},"headline":"Le budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium","datePublished":"2014-02-11T21:48:32+00:00","dateModified":"2014-02-11T23:41:38+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/harpers-olympic-budget-falls-well-short-of-the-podium\/"},"wordCount":1283,"commentCount":1,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"articleSection":["Communiqu\u00e9s"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/","url":"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/","name":"Harper\u2019s Olympic Budget falls well short of the podiumLe budget olympique de Harper reste bien en-de\u00e7\u00e0 du podium | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2014-02-11T21:48:32+00:00","dateModified":"2014-02-11T23:41:38+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/harpers-olympic-budget-falls-well-short-of-the-podium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Harper\u2019s Olympic Budget falls well short of the podium"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f","name":"Craig Cantin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","caption":"Craig Cantin"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/craig-c\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/11541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=11541"}],"version-history":[{"count":3,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/11541\/revisions"}],"predecessor-version":[{"id":11545,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/11541\/revisions\/11545"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=11541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=11541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=11541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}