{"id":12436,"date":"2014-03-28T15:29:26","date_gmt":"2014-03-28T19:29:26","guid":{"rendered":"http:\/\/elizabethmaymp.ca?p=12436"},"modified":"2014-04-10T16:11:18","modified_gmt":"2014-04-10T20:11:18","slug":"fairer-pension-rules","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/","title":{"rendered":"Des r\u00e8gles plus justes sur les pensions"},"content":{"rendered":"<p>Bien des retrait\u00e9s \u2014 anciens militaires, employ\u00e9s de la GRC, fonctionnaires et juges \u2014 n\u2019ont bizarrement pas droit \u00e0 ce que leur pension soit vers\u00e9e \u00e0 leur conjoint survivant. La Loi sur la pension de retraite des Forces canadiennes emp\u00eache les veuves et les veufs de recevoir les prestations de leur \u00e9poux s&#8217;ils se sont mari\u00e9s apr\u00e8s l&#8217;\u00e2ge de 65\u00a0ans. Cette \u00e9trange r\u00e8gle remonte \u00e0 la guerre des Boers, \u00e0 la fin du XIXe\u00a0si\u00e8cle, et visait \u00e0 \u00e9viter que les jeunes femmes de mettre le grappin sur la pension d&#8217;anciens combattants de retour \u00e0 la vie civile. Elle a depuis grandement d\u00e9favoris\u00e9 les \u00e9pouses survivantes partout au pays.<\/p>\n<p>Il faut changer les choses.<\/p>\n<p>Avec le budget f\u00e9d\u00e9ral de 2014, le gouvernement s\u2019attaque au d\u00e9ficit en augmentant les cotisations des retrait\u00e9s f\u00e9d\u00e9raux aux r\u00e9gimes de soins de sant\u00e9. Il dit que le d\u00e9ficit atteindra 2,9\u00a0milliards\u00a0de\u00a0dollars d\u2019ici la fin de l\u2019ann\u00e9e. Si on tient compte du fonds d\u2019urgence de 3 milliards, le budget peut \u00eatre consid\u00e9r\u00e9 comme \u00e9quilibr\u00e9. Or, le budget comporte un plan visant \u00e0 \u00e9conomiser 7,6\u00a0millions\u00a0de\u00a0dollars au cours des six prochaines ann\u00e9es, puisqu\u2019on veut doubler les cotisations des fonctionnaires \u00e0 la retraite, notamment des anciens combattants, des employ\u00e9s de la GRC et de la totalit\u00e9 des employ\u00e9s f\u00e9d\u00e9raux. J\u2019ai re\u00e7u pr\u00e8s de 12lettres d\u2019a\u00een\u00e9s qui me demandent d\u2019emp\u00eacher cette mesure scandaleuse. Or, les conditions de travail, notamment sur la retraite, font partie du contrat conclu entre l\u2019\u00c9tat et les fonctionnaires f\u00e9d\u00e9raux.<\/p>\n<p><a href=\"http:\/\/elizabethmaymp.ca\/fr\/parliament\/questions\/2014\/02\/12\/question-period-defeating-the-deficit\/\">Le 12\u00a0f\u00e9vrier<\/a>, je suis la premi\u00e8re d\u00e9put\u00e9e \u00e0 avoir soulev\u00e9 la question \u00e0 la Chambre des communes. Voici mon \u00e9change de propos avec le premier ministre Harper\u00a0:<\/p>\n<p style=\"padding-left: 30px;\"><em><strong>Elizabeth May \u00a0:<\/strong> Monsieur le Pr\u00e9sident, le premier ministre et son ministre des Finances avaient le choix pour vaincre le d\u00e9ficit. Ils pouvaient aller chercher de l&#8217;argent mort, par exemple les 600\u00a0milliards\u00a0de\u00a0dollars qui tra\u00eenent actuellement dans les comptes bancaires des soci\u00e9t\u00e9s, une somme renversante qui repr\u00e9sente 32\u00a0% de notre PIB, ou bien s&#8217;en prendre aux retrait\u00e9s en vie, notamment aux fonctionnaires f\u00e9d\u00e9raux retrait\u00e9s, en doublant les cotisations au r\u00e9gime de sant\u00e9 et en manquant ainsi \u00e0 sa parole.<\/em><\/p>\n<p style=\"padding-left: 30px;\"><em>Le premier ministre peut-il nous dire pourquoi il a choisi de s\u2019en prendre \u00e0 des retrait\u00e9s en vie au lieu d\u2019aller chercher de l\u2019argent mort?<\/em><\/p>\n<p style=\"padding-left: 30px;\"><em><strong>Le tr\u00e8s honorable Stephen Harper \u00a0:<\/strong> Monsieur le Pr\u00e9sident, nous maintenons \u00e9videmment les taux d&#8217;imposition des soci\u00e9t\u00e9s. Nous nous attendons \u00e0 ce qu&#8217;elles paient leurs imp\u00f4ts et nous les poursuivons en justice lorsqu&#8217;elles omettent de le faire. Toutefois, la question qui a \u00e9t\u00e9 pos\u00e9e concerne les prestations suppl\u00e9mentaires de sant\u00e9 auxquelles les retrait\u00e9s cotisent sur une base volontaire.<\/em><\/p>\n<p style=\"padding-left: 30px;\"><em>Ce que nous disons, c\u2019est qu\u2019il s\u2019agit toujours, selon nous, d\u2019un avantage faisant l\u2019objet de n\u00e9gociations. Nous avons dit tr\u00e8s clairement que dans le cas d\u2019un plan volontaire comme celui-l\u00e0, un plan de luxe, les retrait\u00e9s doivent payer leur juste part du plan, soit 50\u00a0%. Malgr\u00e9 cela, le plan demeurerait l\u2019un des plus avantageux qui existent au pays.<\/em><\/p>\n<p>[CHQa3qiNYpo]<\/p>\n<p>Comme le premier ministre pr\u00e9tend que la question fait toujours l\u2019objet de n\u00e9gociations, je ferai tout mon possible pour que les cotisations au r\u00e9gime de soins de sant\u00e9 demeurent au m\u00eame niveau qu\u2019\u00e0 l\u2019embauche, soit \u00e0 la signature de leur contrat de travail avec leur employeur, le gouvernement f\u00e9d\u00e9ral.<\/p>\n<h2>\u00c9galement dans ce num\u00e9ro\u2026<\/h2>\n<ul>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/supporting-seniors\" target=\"_blank\" rel=\"noopener noreferrer\">Introduction<\/a><\/li>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/supporting-seniors\/are-rrsps-a-solution\" target=\"_blank\" rel=\"noopener noreferrer\">Les REER, vraiment une solution?<\/a><\/li>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/supporting-seniors\/pensions\" target=\"_blank\" rel=\"noopener noreferrer\">Pensions <\/a><\/li>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/supporting-seniors\/fairer-pension-rules\" target=\"_blank\" rel=\"noopener noreferrer\">Des r\u00e8gles plus justes sur les pensions<\/a><\/li>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/supporting-seniors\/dementia-and-alzheimers\" target=\"_blank\" rel=\"noopener noreferrer\">D\u00e9mence et Alzheimer<\/a><\/li>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/supporting-seniors\/health-care-costs\" target=\"_blank\" rel=\"noopener noreferrer\">Co\u00fbts des soins de sant\u00e9<\/a><\/li>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/supporting-seniors\/dying-with-dignity\" target=\"_blank\" rel=\"noopener noreferrer\">Mourir dans la dignit\u00e9<\/a><\/li>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/supporting-seniors\/teachers-institute\" target=\"_blank\" rel=\"noopener noreferrer\">Forum des enseignantes et des enseignants sur la d\u00e9mocratie parlementaire canadienne<\/a><\/li>\n<li><a href=\"http:\/\/www.elizabethmaymp.ca\/fr\/survey\" target=\"_blank\" rel=\"noopener noreferrer\">Votre opinion compte!<\/a><\/li>\n<\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Bien des retrait\u00e9s \u2014 anciens militaires, employ\u00e9s de la GRC, fonctionnaires et juges \u2014 n\u2019ont bizarrement pas droit \u00e0 ce que leur pension soit vers\u00e9e \u00e0 leur conjoint&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[135],"tags":[],"class_list":["post-12436","post","type-post","status-publish","format-standard","hentry","category-householders"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Des r\u00e8gles plus justes sur les pensions | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des r\u00e8gles plus justes sur les pensions | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Bien des retrait\u00e9s \u2014 anciens militaires, employ\u00e9s de la GRC, fonctionnaires et juges \u2014 n\u2019ont bizarrement pas droit \u00e0 ce que leur pension soit vers\u00e9e \u00e0 leur conjoint&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-28T19:29:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-04-10T20:11:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Craig Cantin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Craig Cantin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fairer-pension-rules\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fairer-pension-rules\\\/\"},\"author\":{\"name\":\"Craig Cantin\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\"},\"headline\":\"Des r\u00e8gles plus justes sur les pensions\",\"datePublished\":\"2014-03-28T19:29:26+00:00\",\"dateModified\":\"2014-04-10T20:11:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fairer-pension-rules\\\/\"},\"wordCount\":1177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"articleSection\":[\"Householders\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fairer-pension-rules\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fairer-pension-rules\\\/\",\"name\":\"Fairer Pension Rules Des r\u00e8gles plus justes sur les pensions | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2014-03-28T19:29:26+00:00\",\"dateModified\":\"2014-04-10T20:11:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fairer-pension-rules\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fairer-pension-rules\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fairer-pension-rules\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des r\u00e8gles plus justes sur les pensions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\",\"name\":\"Craig Cantin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"caption\":\"Craig Cantin\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/craig-c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des r\u00e8gles plus justes sur les pensions | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/","og_locale":"en_US","og_type":"article","og_title":"Des r\u00e8gles plus justes sur les pensions | Elizabeth May","og_description":"Bien des retrait\u00e9s \u2014 anciens militaires, employ\u00e9s de la GRC, fonctionnaires et juges \u2014 n\u2019ont bizarrement pas droit \u00e0 ce que leur pension soit vers\u00e9e \u00e0 leur conjoint&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2014-03-28T19:29:26+00:00","article_modified_time":"2014-04-10T20:11:18+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Craig Cantin","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Craig Cantin","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/"},"author":{"name":"Craig Cantin","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f"},"headline":"Des r\u00e8gles plus justes sur les pensions","datePublished":"2014-03-28T19:29:26+00:00","dateModified":"2014-04-10T20:11:18+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/"},"wordCount":1177,"commentCount":0,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"articleSection":["Householders"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/","url":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/","name":"Fairer Pension Rules Des r\u00e8gles plus justes sur les pensions | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2014-03-28T19:29:26+00:00","dateModified":"2014-04-10T20:11:18+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/fairer-pension-rules\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Des r\u00e8gles plus justes sur les pensions"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f","name":"Craig Cantin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","caption":"Craig Cantin"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/craig-c\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/12436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=12436"}],"version-history":[{"count":3,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/12436\/revisions"}],"predecessor-version":[{"id":12521,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/12436\/revisions\/12521"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=12436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=12436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=12436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}