{"id":12626,"date":"2014-05-13T10:54:53","date_gmt":"2014-05-13T14:54:53","guid":{"rendered":"http:\/\/elizabethmaymp.ca?p=12626"},"modified":"2014-05-13T10:54:53","modified_gmt":"2014-05-13T14:54:53","slug":"fair-elections-act-bill-c-23-4","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/","title":{"rendered":"Loi sur l&#8217;int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23)"},"content":{"rendered":"<p><strong>L&#8217;hon. Wayne Easter :<\/strong> Monsieur le Pr\u00e9sident, je remercie la chef du Parti vert de ses observations. Je crois qu&#8217;elle a vis\u00e9 juste lorsqu&#8217;elle a dit en dernier que la possible adoption du projet de loi C-23 serait \u00ab un jour sombre pour la d\u00e9mocratie \u00bb.<\/p>\n<p>[MBEZCkYJmms]<\/p>\n<p>    La d\u00e9put\u00e9e a donn\u00e9 plusieurs exemples. Il y a aussi deux autres \u00e9l\u00e9ments auxquels le gouvernement conservateur a nui. La fa\u00e7on dont le Canada tenait des \u00e9lections, notamment gr\u00e2ce \u00e0 \u00c9lections Canada, a d\u00e9j\u00e0 \u00e9t\u00e9 un mod\u00e8le \u00e0 suivre. La m\u00eame chose peut \u00eatre dite au sujet de Statistique Canada, qui a d\u00e9j\u00e0 \u00e9t\u00e9 l&#8217;un des meilleurs bureaux de statistique du monde, mais qui, depuis que les conservateurs sont au pouvoir, est consid\u00e9r\u00e9 comme l&#8217;un des pires.<\/p>\n<p>    J&#8217;ai deux questions pour la d\u00e9put\u00e9e. Premi\u00e8rement, \u00e9tant donn\u00e9 que le projet de loi C-23 nous emp\u00eache dans une certaine mesure de bien encadrer les \u00e9lections et de faire enqu\u00eate sur les manoeuvres suspectes, permettrait-il \u00e0 un gouvernement d&#8217;acheter ou de voler les \u00e9lections? Deuxi\u00e8mement, devrions-nous demander aux Nations Unies d&#8217;envoyer des observateurs au Canada lors des prochaines \u00e9lections?<\/p>\n<p><strong>Elizabeth May :<\/strong> Monsieur le Pr\u00e9sident, je pr\u00e9sume que le deuxi\u00e8me volet de la question du d\u00e9put\u00e9 de Malpeque \u00e9tait quelque peu ironique. Je me contenterai donc de r\u00e9pondre au premier volet, \u00e0 savoir: devrions-nous \u00eatre inquiets?<br \/>\n    Selon tout ce que j&#8217;ai pu lire \u2014 et je me suis beaucoup int\u00e9ress\u00e9e \u00e0 ce qui s&#8217;est pass\u00e9 en 2008 \u00e0 Saanich\u2014Gulf Islands \u2014, je crois que c&#8217;\u00e9tait un projet-pilote ayant pour but de d\u00e9terminer si le recours \u00e0 des appels automatis\u00e9s pouvait changer le cours des \u00e9lections dans une circonscription. \u00c9lections Canada et la GRC n&#8217;ont pas pu faire la lumi\u00e8re sur cette affaire. La GRC a dit \u00e0 quelques personnes qui ont port\u00e9 plainte qu&#8217;elle ne pouvait pas trouver le responsable de ces appels parce que le num\u00e9ro de t\u00e9l\u00e9phone venait des \u00c9tats-Unis.<\/p>\n<p>    S&#8217;il avait \u00e9t\u00e9 question d&#8217;un producteur de pornographie juv\u00e9nile ou d&#8217;un r\u00e9seau de traite de personnes, j&#8217;ose croire que nous aurions essay\u00e9 de trouver l&#8217;origine de ces appels. Il est inacceptable de dire que nous n&#8217;avons pas pu trouver le responsable parce que le num\u00e9ro utilis\u00e9 vient des \u00c9tats-Unis. C&#8217;est comme s&#8217;il importait peu de savoir qui, de Gary Lunn ou de Briony Penn, a \u00e9t\u00e9 \u00e9lu. Or, c&#8217;est important, et l&#8217;heure est grave pour la d\u00e9mocratie canadienne lorsqu&#8217;une campagne frauduleuse d&#8217;appels automatis\u00e9s peut faire changer le cours des \u00e9lections.<\/p>\n<p>    J&#8217;estime que l&#8217;impossibilit\u00e9 de faire la lumi\u00e8re sur les \u00e9lections de 2008 \u00e0 Saanich\u2014Gulf Islands a donn\u00e9 lieu \u00e0 une utilisation r\u00e9pandue des appels automatis\u00e9s en 2011 pour emp\u00eacher des \u00e9lecteurs de voter. Si nous ne r\u00e9ussissons pas \u00e0 faire la lumi\u00e8re sur ce qui s&#8217;est pass\u00e9 en 2011, j&#8217;ose \u00e0 peine en imaginer les cons\u00e9quences pour les prochaines \u00e9lections g\u00e9n\u00e9rales.<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#8217;hon. Wayne Easter : Monsieur le Pr\u00e9sident, je remercie la chef du Parti vert de ses observations. Je crois qu&#8217;elle a vis\u00e9 juste lorsqu&#8217;elle a dit en dernier&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-12626","post","type-post","status-publish","format-standard","hentry","category-debate"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Loi sur l&#039;int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23) | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loi sur l&#039;int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23) | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"L&#8217;hon. Wayne Easter : Monsieur le Pr\u00e9sident, je remercie la chef du Parti vert de ses observations. Je crois qu&#8217;elle a vis\u00e9 juste lorsqu&#8217;elle a dit en dernier&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-13T14:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Craig Cantin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Craig Cantin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fair-elections-act-bill-c-23-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fair-elections-act-bill-c-23-4\\\/\"},\"author\":{\"name\":\"Craig Cantin\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\"},\"headline\":\"Loi sur l&#8217;int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23)\",\"datePublished\":\"2014-05-13T14:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fair-elections-act-bill-c-23-4\\\/\"},\"wordCount\":967,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"articleSection\":[\"D\u00e9bat\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fair-elections-act-bill-c-23-4\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fair-elections-act-bill-c-23-4\\\/\",\"name\":\"Fair Elections Act (Bill C-23)Loi sur l'int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23) | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2014-05-13T14:54:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fair-elections-act-bill-c-23-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fair-elections-act-bill-c-23-4\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/fair-elections-act-bill-c-23-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fair Elections Act (Bill C-23)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\",\"name\":\"Craig Cantin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"caption\":\"Craig Cantin\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/craig-c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loi sur l'int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23) | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/","og_locale":"en_US","og_type":"article","og_title":"Loi sur l'int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23) | Elizabeth May","og_description":"L&#8217;hon. Wayne Easter : Monsieur le Pr\u00e9sident, je remercie la chef du Parti vert de ses observations. Je crois qu&#8217;elle a vis\u00e9 juste lorsqu&#8217;elle a dit en dernier&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2014-05-13T14:54:53+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Craig Cantin","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Craig Cantin","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/fair-elections-act-bill-c-23-4\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fair-elections-act-bill-c-23-4\/"},"author":{"name":"Craig Cantin","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f"},"headline":"Loi sur l&#8217;int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23)","datePublished":"2014-05-13T14:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/fair-elections-act-bill-c-23-4\/"},"wordCount":967,"commentCount":0,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"articleSection":["D\u00e9bat"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/","url":"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/","name":"Fair Elections Act (Bill C-23)Loi sur l'int\u00e9grit\u00e9 des \u00e9lections (le projet de loi C-23) | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2014-05-13T14:54:53+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/fair-elections-act-bill-c-23-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Fair Elections Act (Bill C-23)"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f","name":"Craig Cantin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","caption":"Craig Cantin"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/craig-c\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/12626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=12626"}],"version-history":[{"count":1,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/12626\/revisions"}],"predecessor-version":[{"id":12627,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/12626\/revisions\/12627"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=12626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=12626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=12626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}