{"id":17938,"date":"2017-03-21T16:52:24","date_gmt":"2017-03-21T20:52:24","guid":{"rendered":"http:\/\/elizabethmaymp.ca?p=17938"},"modified":"2017-03-23T16:53:52","modified_gmt":"2017-03-23T20:53:52","slug":"statement-on-international-day-for-the-elimination-of-racial-discrimination-2","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/","title":{"rendered":"D\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale"},"content":{"rendered":"<p>Mme. May croit que le Canada est plus fort quand il est inclusif, uni et libre de toute forme de discrimination raciale.<\/p>\n<p>\u00ab Face au climat politique de plus en plus toxique qui se d\u00e9veloppe sous l\u2019administration Trump, le Canada doit devenir un d\u00e9fenseur des droits de la personne sur la sc\u00e8ne internationale, et s\u2019opposer fortement \u00e0 toute politique qui encourage \u2013 directement ou indirectement \u2013 toute manifestation de racisme, de discrimination raciale ou de x\u00e9nophobie \u00e0 l\u2019endroit des r\u00e9fugi\u00e9s et des immigrants, a affirm\u00e9 Elizabeth May, cheffe du Parti vert du Canada et d\u00e9put\u00e9e de Saanich-Gulf Islands.<\/p>\n<p>\u00ab Alors que les \u00c9tats-Unis s\u2019isolent de plus en plus et que le pr\u00e9sident Trump d\u00e9cr\u00e8te des interdictions discriminatoires en mati\u00e8re d\u2019immigration, nous devons absolument d\u00e9noncer ces abus de pouvoir. Les Canadiens ne se plieront pas devant le racisme d\u00e9guis\u00e9 sous des mesures de s\u00e9curit\u00e9 nationale. Le Canada a prouv\u00e9 qu\u2019il est possible d\u2019assurer la s\u00e9curit\u00e9 d\u2019un pays tout en continuant de favoriser la diversit\u00e9 ethnique qui fait de notre pays un flambeau d&#8217;espoir pour le reste du monde. \u00bb<\/p>","protected":false},"excerpt":{"rendered":"<p>Mme. May croit que le Canada est plus fort quand il est inclusif, uni et libre de toute forme de discrimination raciale. \u00ab Face au climat politique de&hellip;<\/p>\n","protected":false},"author":1381,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[90,11],"tags":[],"class_list":["post-17938","post","type-post","status-publish","format-standard","hentry","category-press-releases","category-publications"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Mme. May croit que le Canada est plus fort quand il est inclusif, uni et libre de toute forme de discrimination raciale. \u00ab Face au climat politique de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-21T20:52:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-23T20:53:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elizabeth May\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elizabeth May\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\\\/\"},\"author\":{\"name\":\"Elizabeth May\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/8ad70c936dfbb0f3a3af6907c5fdd64c\"},\"headline\":\"D\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale\",\"datePublished\":\"2017-03-21T20:52:24+00:00\",\"dateModified\":\"2017-03-23T20:53:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\\\/\"},\"wordCount\":359,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"articleSection\":[\"Communiqu\u00e9s\",\"Publications\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\\\/\",\"name\":\"Statement on International Day for the Elimination of Racial DiscriminationD\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2017-03-21T20:52:24+00:00\",\"dateModified\":\"2017-03-23T20:53:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statement on International Day for the Elimination of Racial Discrimination\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/8ad70c936dfbb0f3a3af6907c5fdd64c\",\"name\":\"Elizabeth May\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"caption\":\"Elizabeth May\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/outreach-coordinator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/","og_locale":"en_US","og_type":"article","og_title":"D\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale | Elizabeth May","og_description":"Mme. May croit que le Canada est plus fort quand il est inclusif, uni et libre de toute forme de discrimination raciale. \u00ab Face au climat politique de&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2017-03-21T20:52:24+00:00","article_modified_time":"2017-03-23T20:53:52+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Elizabeth May","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Elizabeth May","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/"},"author":{"name":"Elizabeth May","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/8ad70c936dfbb0f3a3af6907c5fdd64c"},"headline":"D\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale","datePublished":"2017-03-21T20:52:24+00:00","dateModified":"2017-03-23T20:53:52+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/"},"wordCount":359,"commentCount":1,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"articleSection":["Communiqu\u00e9s","Publications"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/","url":"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/","name":"Statement on International Day for the Elimination of Racial DiscriminationD\u00e9claration \u00e0 l\u2019occasion de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la discrimination raciale | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2017-03-21T20:52:24+00:00","dateModified":"2017-03-23T20:53:52+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/statement-on-international-day-for-the-elimination-of-racial-discrimination-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Statement on International Day for the Elimination of Racial Discrimination"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/8ad70c936dfbb0f3a3af6907c5fdd64c","name":"Elizabeth May","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","caption":"Elizabeth May"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/outreach-coordinator\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/17938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/1381"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=17938"}],"version-history":[{"count":3,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/17938\/revisions"}],"predecessor-version":[{"id":17941,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/17938\/revisions\/17941"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=17938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=17938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=17938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}