{"id":1982,"date":"2011-11-29T11:16:51","date_gmt":"2011-11-29T16:16:51","guid":{"rendered":"http:\/\/dev2.elizabethmaymp.ca\/?p=1982"},"modified":"2011-12-17T22:38:23","modified_gmt":"2011-12-18T03:38:23","slug":"safe-streets-and-communities-act-h-2","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/","title":{"rendered":"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H)"},"content":{"rendered":"<p><strong>Mme Elizabeth May:<\/strong> Monsieur le Pr\u00e9sident, j&#8217;aimerais que la d\u00e9put\u00e9e pr\u00e9cise sa pens\u00e9e sur l&#8217;utilit\u00e9 du projet de loi pour prot\u00e9ger les enfants. Est-il utile ou non? Je souligne que, parmi les gens qui ont s\u00e9v\u00e8rement critiqu\u00e9 le projet de loi se trouvent la Soci\u00e9t\u00e9 canadienne de p\u00e9diatrie ainsi que le Conseil canadien des d\u00e9fenseurs des enfants et des jeunes, dont les objections concernent en particulier les modifications \u00e0 la Loi sur le syst\u00e8me de justice p\u00e9nale pour les adolescents.<\/p>\n<p>[iC9z1uMaxi0]<\/p>\n<p>Comment pouvons-nous nous assurer de prot\u00e9ger les jeunes, comme tout le monde dans cette enceinte souhaite le faire? Nous ne voulons pas que les enfants courent le risque de tomber entre les griffes de pr\u00e9dateurs sexuels. Nous ne voulons pas qu&#8217;ils puissent \u00eatre exploit\u00e9s pour produire de la pornographie juv\u00e9nile. Cependant, nous ne voulons pas que soit adopt\u00e9 un projet de loi que les experts de l&#8217;aide \u00e0 l&#8217;enfance jugent aussi lamentable.<\/p>\n<p><strong>Mme Jean Crowder:<\/strong> Monsieur le Pr\u00e9sident, permettez-moi de citer encore ce que dit le rapport \u00e0 propos de l&#8217;\u00e9ducation de la petite enfance. Voici ce qui est \u00e9crit:<\/p>\n<blockquote><p><em>Des \u00e9tudes sur le sujet ont montr\u00e9 l&#8217;une apr\u00e8s l&#8217;autre qu&#8217;une \u00e9ducation de haute qualit\u00e9 pendant la petite enfance r\u00e9duit le taux de d\u00e9linquance chez les enfants d\u00e9favoris\u00e9s et augmente leur taux de r\u00e9ussite \u00e0 terminer le secondaire et \u00e0 trouver un emploi. En fait, l&#8217;\u00e9ducation de qualit\u00e9 de la petite enfance profite \u00e0 tous les enfants, peu importe leur classe sociale ou la situation d&#8217;emploi parental. L&#8217;une des raisons est que l&#8217;\u00e9ducation de qualit\u00e9 de la petite enfance donne l&#8217;occasion d&#8217;identifier et d&#8217;intervenir tr\u00e8s t\u00f4t dans le cas d&#8217;enfants avec des besoins sp\u00e9ciaux.<\/em><\/p><\/blockquote>\n<p>Je le r\u00e9p\u00e8te, nous devons nous int\u00e9resser aux causes profondes de la criminalit\u00e9, qui ne semblent pas figurer dans le programme du gouvernement. Nous devons parler des interventions pr\u00e9coces. Nous devons parler de l&#8217;aide \u00e0 fournir aux enfants, qu&#8217;ils aient des besoins sp\u00e9ciaux, qu&#8217;ils \u00e9prouvent des difficult\u00e9s d&#8217;apprentissage ou qu&#8217;ils n&#8217;aient pas, au foyer, toute l&#8217;aide dont ils auraient besoin. Les interventions pr\u00e9coces sont n\u00e9cessaires pour aider ces enfants de mani\u00e8re \u00e0 ce qu&#8217;ils n&#8217;aient pas un jour des d\u00e9m\u00eal\u00e9s avec le syst\u00e8me de justice p\u00e9nale.<\/p>\n<p>Comme l&#8217;indique l&#8217;article, ce constat s&#8217;applique aux enfants de toutes les classes sociales, et non uniquement aux enfants pauvres.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mme Elizabeth May: Monsieur le Pr\u00e9sident, j&#8217;aimerais que la d\u00e9put\u00e9e pr\u00e9cise sa pens\u00e9e sur l&#8217;utilit\u00e9 du projet de loi pour prot\u00e9ger les enfants. Est-il utile ou non? Je&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[20],"tags":[13,149,124,325],"class_list":["post-1982","post","type-post","status-publish","format-standard","hentry","category-debate","tag-justice","tag-omnibus-crime-bill","tag-youth","tag-youth-criminal-justice-act"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H) | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H) | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Mme Elizabeth May: Monsieur le Pr\u00e9sident, j&#8217;aimerais que la d\u00e9put\u00e9e pr\u00e9cise sa pens\u00e9e sur l&#8217;utilit\u00e9 du projet de loi pour prot\u00e9ger les enfants. Est-il utile ou non? Je&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-29T16:16:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-12-18T03:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Craig Cantin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Craig Cantin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/safe-streets-and-communities-act-h-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/safe-streets-and-communities-act-h-2\\\/\"},\"author\":{\"name\":\"Craig Cantin\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\"},\"headline\":\"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H)\",\"datePublished\":\"2011-11-29T16:16:51+00:00\",\"dateModified\":\"2011-12-18T03:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/safe-streets-and-communities-act-h-2\\\/\"},\"wordCount\":762,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"keywords\":[\"Justice\",\"La loi omnibus sur le crime\",\"Les jeunes\",\"La Loi sur le syst\u00e8me de justice p\u00e9nale pour les adolescents\"],\"articleSection\":[\"D\u00e9bat\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-h-2\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-h-2\\\/\",\"name\":\"Safe Streets and Communities Act (H)Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H) | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2011-11-29T16:16:51+00:00\",\"dateModified\":\"2011-12-18T03:38:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-h-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-h-2\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-h-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Safe Streets and Communities Act (H)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\",\"name\":\"Craig Cantin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"caption\":\"Craig Cantin\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/craig-c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H) | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/","og_locale":"en_US","og_type":"article","og_title":"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H) | Elizabeth May","og_description":"Mme Elizabeth May: Monsieur le Pr\u00e9sident, j&#8217;aimerais que la d\u00e9put\u00e9e pr\u00e9cise sa pens\u00e9e sur l&#8217;utilit\u00e9 du projet de loi pour prot\u00e9ger les enfants. Est-il utile ou non? Je&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2011-11-29T16:16:51+00:00","article_modified_time":"2011-12-18T03:38:23+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Craig Cantin","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Craig Cantin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/safe-streets-and-communities-act-h-2\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/safe-streets-and-communities-act-h-2\/"},"author":{"name":"Craig Cantin","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f"},"headline":"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H)","datePublished":"2011-11-29T16:16:51+00:00","dateModified":"2011-12-18T03:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/safe-streets-and-communities-act-h-2\/"},"wordCount":762,"commentCount":0,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"keywords":["Justice","La loi omnibus sur le crime","Les jeunes","La Loi sur le syst\u00e8me de justice p\u00e9nale pour les adolescents"],"articleSection":["D\u00e9bat"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/","url":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/","name":"Safe Streets and Communities Act (H)Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s (H) | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2011-11-29T16:16:51+00:00","dateModified":"2011-12-18T03:38:23+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-h-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Safe Streets and Communities Act (H)"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f","name":"Craig Cantin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","caption":"Craig Cantin"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/craig-c\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/1982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=1982"}],"version-history":[{"count":4,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/1982\/revisions"}],"predecessor-version":[{"id":2124,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/1982\/revisions\/2124"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=1982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=1982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=1982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}