{"id":24500,"date":"2020-04-17T09:46:01","date_gmt":"2020-04-17T13:46:01","guid":{"rendered":"http:\/\/elizabethmaymp.ca\/?p=24500"},"modified":"2021-02-10T09:47:52","modified_gmt":"2021-02-10T14:47:52","slug":"greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/","title":{"rendered":"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada"},"content":{"rendered":"<p>17 avril 2020<\/p>\n<p>OTTAWA &#8211; Le Parti vert du Canada est pr\u00e9occup\u00e9 par l&#8217;augmentation des \u00e9missions de gaz \u00e0 effet de serre (GES) du Canada pour 2018, comme le souligne le rapport d&#8217;inventaire national soumis aux Nations unies cette semaine par Environnement et changements climatiques Canada (ECCC). Le Canada a enregistr\u00e9 729 millions de tonnes d&#8217;\u00e9missions de GES pour 2018, soit une augmentation de 15 millions de tonnes par rapport \u00e0 2017.<\/p>\n<p>\u00ab Il est \u00e9vident qu&#8217;en cette p\u00e9riode sans pr\u00e9c\u00e9dent durant laquelle tous nos efforts doivent se concentrer sur la menace que repr\u00e9sente la COVID-19 pour la sant\u00e9 humaine, il peut sembler inappropri\u00e9 de soulever des pr\u00e9occupations climatiques, \u00bb  a d\u00e9clar\u00e9 la chef parlementaire des Verts Elizabeth May (d\u00e9put\u00e9e de Saanich-Gulf Islands). \u00ab Cependant, cette nouvelle selon laquelle les efforts du Canada entrepris \u00e0 la fin de 2018 sont en train d&#8217;\u00e9chouer doit \u00eatre signal\u00e9e. \u00c9tant donn\u00e9 que les \u00e9missions ont augment\u00e9 en 2018, nos plans climatiques suite \u00e0 la pand\u00e9mie doivent \u00eatre beaucoup plus agressifs. Nous devons maintenir notre approche collective face \u00e0 la pand\u00e9mie pour relever le d\u00e9fi climatique. Nous devons donner la priorit\u00e9 aux investissements dans une relance \u00e0 faible intensit\u00e9 de carbone. \u00bb<\/p>\n<p>ECCC est charg\u00e9 d&#8217;\u00e9laborer et de communiquer des inventaires de GES fiables, pr\u00e9cis et opportuns dans le cadre de ses obligations au titre de la Convention-cadre des Nations unies sur les changements climatiques (CCNUCC).<\/p>\n<p>Mme May souligne qu&#8217;aux termes de l&#8217;accord de Paris, le Canada aurait d\u00fb soumettre un nouvel objectif d&#8217;\u00e9missions &#8211; connu sous le nom de contribution nationale d\u00e9termin\u00e9e (CND) &#8211; plus t\u00f4t cette ann\u00e9e. \u00ab M\u00eame si la COP 26 a \u00e9t\u00e9 report\u00e9e \u00e0 2021, l&#8217;objectif am\u00e9lior\u00e9 du Canada est pr\u00e9vu pour 2020. Le 9 f\u00e9vrier \u00e9tait la date limite pour que le Canada et les autres pays soumettent leur CND. Malheureusement, le Canada n&#8217;a pas respect\u00e9 cette date limite et nous sommes maintenant au milieu d&#8217;une pand\u00e9mie qui, on le comprend, fait appel \u00e0 toutes nos ressources. Toutefois, pour \u00eatre responsables et assumer notre juste part, nous devons r\u00e9duire nos \u00e9missions de gaz \u00e0 effet de serre de 60 % par rapport aux niveaux de 2005 d&#8217;ici 2030. J&#8217;esp\u00e8re qu&#8217;une fois que nous serons en mesure de recentrer notre attention sur l&#8217;urgence climatique, tous les minist\u00e8res redoubleront d&#8217;efforts pour int\u00e9grer une meilleure adaptation \u00e0 la crise climatique dans leurs portefeuilles. \u00bb<\/p>\n<p>Mission possible &#8211; Le plan d\u2019action climatique du Parti vert trace une voie solide pour une transition juste et \u00e9quitable vers une \u00e9conomie verte.  <\/p>\n<p>\u00ab Lorsque nous sortirons de cette pand\u00e9mie et que les efforts de relance s\u2019amorceront, un plan solide pour une transition \u00e9nerg\u00e9tique juste et \u00e9quitable sera essentiel, \u00bb a d\u00e9clar\u00e9 la chef par int\u00e9rim du Parti vert Jo-Ann Roberts. \u00ab Cela offrira aux Canadiens une r\u00e9elle opportunit\u00e9 de dynamiser le secteur de l&#8217;\u00e9nergie propre, ce qui r\u00e9duira consid\u00e9rablement nos \u00e9missions et nous permettra d&#8217;atteindre les objectifs fix\u00e9s par le Groupe d&#8217;experts intergouvernemental sur l&#8217;\u00e9volution du climat (GIEC). Cette crise tragique nous a rappel\u00e9 l&#8217;importance de la collaboration nationale et mondiale. Elle a \u00e9galement d\u00e9montr\u00e9 la capacit\u00e9 des gouvernements \u00e0 s&#8217;adapter et \u00e0 faire preuve d&#8217;un leadership fort en situation de crise. Nous pouvons utiliser cette exp\u00e9rience comme un mod\u00e8le pour aller de l&#8217;avant et proscrire nos anciennes m\u00e9thodes. \u00bb<\/p>\n<p># # #<\/p>\n<p>Pour plus d&#8217;informations ou pour organiser une entrevue :<\/p>\n<p>Rosie Emery<\/p>\n<p>Attach\u00e9e de presse<\/p>\n<p>613-562-4916, poste 204<\/p>\n<p>rosie.emery@partivert.ca<\/p>","protected":false},"excerpt":{"rendered":"<p>17 avril 2020 OTTAWA &#8211; Le Parti vert du Canada est pr\u00e9occup\u00e9 par l&#8217;augmentation des \u00e9missions de gaz \u00e0 effet de serre (GES) du Canada pour 2018, comme&hellip;<\/p>\n","protected":false},"author":1381,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[90,11],"tags":[46,2487,1722],"class_list":["post-24500","post","type-post","status-publish","format-standard","hentry","category-press-releases","category-publications","tag-climate-change","tag-covid19","tag-emissions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"17 avril 2020 OTTAWA &#8211; Le Parti vert du Canada est pr\u00e9occup\u00e9 par l&#8217;augmentation des \u00e9missions de gaz \u00e0 effet de serre (GES) du Canada pour 2018, comme&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-17T13:46:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T14:47:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elizabeth May\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elizabeth May\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\\\/\"},\"author\":{\"name\":\"Elizabeth May\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/8ad70c936dfbb0f3a3af6907c5fdd64c\"},\"headline\":\"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada\",\"datePublished\":\"2020-04-17T13:46:01+00:00\",\"dateModified\":\"2021-02-10T14:47:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\\\/\"},\"wordCount\":1098,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"keywords\":[\"Changement climatique\",\"covid19\",\"Emissions\"],\"articleSection\":[\"Communiqu\u00e9s\",\"Publications\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\\\/\",\"name\":\"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2020-04-17T13:46:01+00:00\",\"dateModified\":\"2021-02-10T14:47:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/8ad70c936dfbb0f3a3af6907c5fdd64c\",\"name\":\"Elizabeth May\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"caption\":\"Elizabeth May\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/outreach-coordinator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/","og_locale":"en_US","og_type":"article","og_title":"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada | Elizabeth May","og_description":"17 avril 2020 OTTAWA &#8211; Le Parti vert du Canada est pr\u00e9occup\u00e9 par l&#8217;augmentation des \u00e9missions de gaz \u00e0 effet de serre (GES) du Canada pour 2018, comme&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2020-04-17T13:46:01+00:00","article_modified_time":"2021-02-10T14:47:52+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Elizabeth May","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Elizabeth May","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/"},"author":{"name":"Elizabeth May","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/8ad70c936dfbb0f3a3af6907c5fdd64c"},"headline":"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada","datePublished":"2020-04-17T13:46:01+00:00","dateModified":"2021-02-10T14:47:52+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/"},"wordCount":1098,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"keywords":["Changement climatique","covid19","Emissions"],"articleSection":["Communiqu\u00e9s","Publications"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/","url":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/","name":"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2020-04-17T13:46:01+00:00","dateModified":"2021-02-10T14:47:52+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/greens-disturbed-by-latest-report-on-canadas-greenhouse-gas-emissions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Verts pr\u00e9occup\u00e9s par le dernier rapport sur les \u00e9missions de gaz \u00e0 effet de serre au Canada"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/8ad70c936dfbb0f3a3af6907c5fdd64c","name":"Elizabeth May","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","caption":"Elizabeth May"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/outreach-coordinator\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/24500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/1381"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=24500"}],"version-history":[{"count":1,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/24500\/revisions"}],"predecessor-version":[{"id":24501,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/24500\/revisions\/24501"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=24500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=24500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=24500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}