{"id":26288,"date":"2022-04-07T07:56:02","date_gmt":"2022-04-07T14:56:02","guid":{"rendered":"https:\/\/elizabethmaymp.ca\/?p=26288"},"modified":"2022-04-08T07:58:03","modified_gmt":"2022-04-08T14:58:03","slug":"green-party-of-canada-response-to-budget-2022","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/","title":{"rendered":"R\u00e9action du Parti vert du Canada au budget de 2022"},"content":{"rendered":"<p>7 avril 2022<\/p>\n<p>OTTAWA &#8211; Le budget 2022 du gouvernement f\u00e9d\u00e9ral inclut des engagements prometteurs en mati\u00e8re de l\u00e9gislation visant \u00e0 aider la population canadienne en mati\u00e8re d\u2019accessibilit\u00e9 financi\u00e8re, mais ignore la r\u00e9alit\u00e9 de la crise climatique, qui a des r\u00e9percussions sur les gens d&#8217;un oc\u00e9an \u00e0 l&#8217;autre.<\/p>\n<p>\u00ab Il s\u2019agit d\u2019un budget socialement progressiste \u00e0 bien des \u00e9gards, mais nous risquons de ne pas atteindre nos objectifs climatiques parce que ces investissements sont bas\u00e9s sur les mauvaises cibles \u00bb, a d\u00e9clar\u00e9 la chef parlementaire du Parti vert du Canada Elizabeth May (d\u00e9put\u00e9e, Saanich-Gulf Islands). \u00ab Nous n&#8217;avons aucun espoir de nous maintenir \u00e0 une augmentation de 1,5 degr\u00e9 des temp\u00e9ratures mondiales \u00bb.<\/p>\n<p>Le budget survient quelques jours \u00e0 peine apr\u00e8s que le dernier rapport du Groupe d&#8217;experts intergouvernemental sur l&#8217;\u00e9volution du climat (GIEC) ait lanc\u00e9 un avertissement s\u00e9v\u00e8re selon lequel le monde doit rapidement abandonner les combustibles fossiles ou faire face \u00e0 une catastrophe climatique. Le budget pr\u00e9voit des milliards pour une nouvelle subvention pour le p\u00e9trole et le gaz, \u00e9clipsant ainsi d&#8217;autres initiatives en faveur du climat.<\/p>\n<p>\u00ab Nous sommes en voie de rendre la plan\u00e8te inhabitable et nous avons en quelque sorte d\u00e9cid\u00e9 que nous en savons plus que le GIEC \u00bb, a d\u00e9clar\u00e9 Mme May.<\/p>\n<p>Le gouvernement s&#8217;engage \u00e9galement \u00e0 introduire une l\u00e9gislation pour les garderies, l&#8217;assurance-m\u00e9dicaments et les soins dentaires pour les personnes \u00e0 faible revenu, des programmes que le Parti vert d\u00e9fend depuis des ann\u00e9es.<\/p>\n<p>\u00ab La communaut\u00e9 des personnes en situation de handicap est tr\u00e8s d\u00e9\u00e7ue, car elle a demand\u00e9 au gouvernement d&#8217;acc\u00e9l\u00e9rer la mise en place d&#8217;une prestation canadienne pour personnes vivant avec un handicap. Il n&#8217;en a m\u00eame pas \u00e9t\u00e9 question \u00bb, a d\u00e9clar\u00e9 Mike Morrice (d\u00e9put\u00e9 de Kitchener Centre). \u00ab Au lieu de cela, on se concentre uniquement sur un petit montant d&#8217;argent pour une strat\u00e9gie d&#8217;emploi, comme si la seule valeur que les personnes vivant avec un handicap offrent \u00e0 notre soci\u00e9t\u00e9 est leur aptitude au travail. \u00bb<\/p>\n<p>Le Parti vert se r\u00e9jouit de voir un investissement dans la construction de 6 000 nouveaux logements coop\u00e9ratifs, une \u00e9chelle qui n&#8217;a pas \u00e9t\u00e9 vue depuis les ann\u00e9es 1980.<\/p>\n<p>\u00ab Il n&#8217;existe pas de solution miracle pour r\u00e9soudre la crise du logement, mais un m\u00e9lange d&#8217;investissements et de politiques dans ce budget offre un certain espoir \u00bb, a d\u00e9clar\u00e9 M. Morrice. \u00ab Il est prometteur de voir un engagement \u00e0 mettre fin aux ench\u00e8res \u00e0 l&#8217;aveuglette et \u00e0 taxer plus \u00e9quitablement les achats de maisons. Nous devons veiller \u00e0 ce que le logement soit pour les gens un lieu de vie, et non une marchandise que les investisseurs peuvent n\u00e9gocier. \u00bb <\/p>\n<p>Une autre occasion manqu\u00e9e est le manque d&#8217;investissement dans les services de transport public.<\/p>\n<p>\u00ab Nous perdons des services d&#8217;autobus dans l\u2019ensemble du pays \u00bb, a d\u00e9clar\u00e9 le chef int\u00e9rimaire du Parti vert du Canada, Amita Kuttner. \u00ab L&#8217;augmentation du transport entre les communaut\u00e9s aiderait notre population vieillissante, cr\u00e9erait des emplois et jouerait un r\u00f4le important dans la lutte contre le changement climatique. En choisissant de ne pas investir, surtout dans les r\u00e9gions rurales, non seulement nous for\u00e7ons les gens \u00e0 prendre leur voiture, mais nous ne r\u00e9pondons pas \u00e0 l&#8217;une des principales recommandations de l&#8217;Enqu\u00eate nationale sur les femmes et les filles autochtones et les personnes bispirituelles disparues et assassin\u00e9es. \u00bb<\/p>\n<p>####<\/p>\n<p>Pour plus d&#8217;informations ou pour organiser une entrevue :<br \/>\nJohn Chenery<br \/>\nMedia@partivert.ca<br \/>\n1-613-562-4916 poste 215<\/p>","protected":false},"excerpt":{"rendered":"<p>7 avril 2022 OTTAWA &#8211; Le budget 2022 du gouvernement f\u00e9d\u00e9ral inclut des engagements prometteurs en mati\u00e8re de l\u00e9gislation visant \u00e0 aider la population canadienne en mati\u00e8re d\u2019accessibilit\u00e9&hellip;<\/p>\n","protected":false},"author":1381,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[90,11],"tags":[],"class_list":["post-26288","post","type-post","status-publish","format-standard","hentry","category-press-releases","category-publications"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9action du Parti vert du Canada au budget de 2022 | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9action du Parti vert du Canada au budget de 2022 | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"7 avril 2022 OTTAWA &#8211; Le budget 2022 du gouvernement f\u00e9d\u00e9ral inclut des engagements prometteurs en mati\u00e8re de l\u00e9gislation visant \u00e0 aider la population canadienne en mati\u00e8re d\u2019accessibilit\u00e9&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-07T14:56:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-08T14:58:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elizabeth May\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elizabeth May\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/green-party-of-canada-response-to-budget-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/green-party-of-canada-response-to-budget-2022\\\/\"},\"author\":{\"name\":\"Elizabeth May\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/8ad70c936dfbb0f3a3af6907c5fdd64c\"},\"headline\":\"R\u00e9action du Parti vert du Canada au budget de 2022\",\"datePublished\":\"2022-04-07T14:56:02+00:00\",\"dateModified\":\"2022-04-08T14:58:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/green-party-of-canada-response-to-budget-2022\\\/\"},\"wordCount\":1075,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"articleSection\":[\"Communiqu\u00e9s\",\"Publications\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/green-party-of-canada-response-to-budget-2022\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/green-party-of-canada-response-to-budget-2022\\\/\",\"name\":\"R\u00e9action du Parti vert du Canada au budget de 2022 | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2022-04-07T14:56:02+00:00\",\"dateModified\":\"2022-04-08T14:58:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/green-party-of-canada-response-to-budget-2022\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/green-party-of-canada-response-to-budget-2022\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/green-party-of-canada-response-to-budget-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Green Party of Canada Response to Budget 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/8ad70c936dfbb0f3a3af6907c5fdd64c\",\"name\":\"Elizabeth May\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"caption\":\"Elizabeth May\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/outreach-coordinator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9action du Parti vert du Canada au budget de 2022 | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/","og_locale":"en_US","og_type":"article","og_title":"R\u00e9action du Parti vert du Canada au budget de 2022 | Elizabeth May","og_description":"7 avril 2022 OTTAWA &#8211; Le budget 2022 du gouvernement f\u00e9d\u00e9ral inclut des engagements prometteurs en mati\u00e8re de l\u00e9gislation visant \u00e0 aider la population canadienne en mati\u00e8re d\u2019accessibilit\u00e9&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2022-04-07T14:56:02+00:00","article_modified_time":"2022-04-08T14:58:03+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Elizabeth May","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Elizabeth May","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/green-party-of-canada-response-to-budget-2022\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/green-party-of-canada-response-to-budget-2022\/"},"author":{"name":"Elizabeth May","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/8ad70c936dfbb0f3a3af6907c5fdd64c"},"headline":"R\u00e9action du Parti vert du Canada au budget de 2022","datePublished":"2022-04-07T14:56:02+00:00","dateModified":"2022-04-08T14:58:03+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/green-party-of-canada-response-to-budget-2022\/"},"wordCount":1075,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"articleSection":["Communiqu\u00e9s","Publications"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/","url":"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/","name":"R\u00e9action du Parti vert du Canada au budget de 2022 | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2022-04-07T14:56:02+00:00","dateModified":"2022-04-08T14:58:03+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/green-party-of-canada-response-to-budget-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Green Party of Canada Response to Budget 2022"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/8ad70c936dfbb0f3a3af6907c5fdd64c","name":"Elizabeth May","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","caption":"Elizabeth May"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/outreach-coordinator\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/26288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/1381"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=26288"}],"version-history":[{"count":1,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/26288\/revisions"}],"predecessor-version":[{"id":26289,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/26288\/revisions\/26289"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=26288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=26288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=26288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}