{"id":26497,"date":"2022-06-07T23:31:52","date_gmt":"2022-06-08T06:31:52","guid":{"rendered":"https:\/\/elizabethmaymp.ca\/?p=26497"},"modified":"2022-06-16T07:18:19","modified_gmt":"2022-06-16T14:18:19","slug":"small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/","title":{"rendered":"Les PRM ne font pas partie d&#8217;aucune solution \u00e0 la crise climatique"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/vYjVR8PxjGw\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Elizabeth May (Saanich\u2014Gulf Islands)<br \/>\n2022-06-07 23:31 [p.6306]<\/p>\n<p>Monsieur le Pr\u00e9sident, je suis heureuse de prendre la parole aujourd&#8217;hui dans le cadre du d\u00e9bat d&#8217;ajournement. Je dois dire que l&#8217;heure est dr\u00f4lement appropri\u00e9e. Mon intervention fait suite \u00e0 une question que j&#8217;ai pos\u00e9e \u00e0 la p\u00e9riode des questions du 2 mai concernant ce qu&#8217;on appelle les petits r\u00e9acteurs modulaires et leur lien avec la prolif\u00e9ration des armes nucl\u00e9aires. Il tombe donc \u00e0 point qu&#8217;il soit presque minuit. Cela me rappelle clairement cette chose que l&#8217;on appelle l&#8217;horloge de l&#8217;apocalypse, dont la mise \u00e0 jour est assur\u00e9e par le Bulletin of the Atomic Scientists. Je viens de v\u00e9rifier, et elle indique que nous sommes \u00ab \u00e0 100 secondes d&#8217;atteindre minuit \u00bb, \u00e9tant donn\u00e9 la combinaison de facteurs que sont les menaces accrues de d\u00e9clenchement d&#8217;une guerre nucl\u00e9aire provoqu\u00e9e par l&#8217;invasion de l&#8217;Ukraine par la Russie et le danger consid\u00e9rable que repr\u00e9sente la crise du climat pour l&#8217;ensemble de la plan\u00e8te.<\/p>\n<p>Ces probl\u00e8mes sont li\u00e9s, et j&#8217;en ai parl\u00e9 dans ma question \u00e0 la Chambre le 2 mai. La r\u00e9ponse qu&#8217;avait alors donn\u00e9e le ministre des Ressources naturelles \u00e9tait insuffisante. Voil\u00e0 pourquoi je soul\u00e8ve la question de nouveau ce soir.<\/p>\n<p>Les soi-disant petits r\u00e9acteurs modulaires ne font partie d&#8217;aucune solution \u00e0 la crise du climat. De plus, ils n&#8217;ont pas fait leurs preuves et sont, essentiellement, exp\u00e9rimentaux. Enfin, j&#8217;attire une fois de plus l&#8217;attention de la Chambre sur le risque de prolif\u00e9ration des armes nucl\u00e9aires.<\/p>\n<p>Je vais passer ces trois points en revue. Le ministre des Ressources naturelles a souvent dit dans cette enceinte que toutes les voies vers des solutions climatiques comportaient de petits r\u00e9acteurs modulaires. C&#8217;est tout simplement faux. La r\u00e9duction des gaz \u00e0 effet de serre passe par l&#8217;\u00e9limination progressive des combustibles fossiles, l&#8217;annulation du projet de l&#8217;ol\u00e9oduc TMX et l&#8217;abandon de Bay du Nord. Ce sont des choses tangibles qui n&#8217;ont rien \u00e0 voir avec le nucl\u00e9aire. Le nucl\u00e9aire est en fait un obstacle. Il est tr\u00e8s co\u00fbteux. Par tonne de carbone de r\u00e9duction, c&#8217;est \u00e0 peu pr\u00e8s la voie la plus co\u00fbteuse que nous puissions emprunter. Il faut aussi beaucoup de temps avant de voir les r\u00e9sultats d&#8217;une d\u00e9cision de recourir au nucl\u00e9aire.<\/p>\n<p>Le fait que ces r\u00e9acteurs ne soient pas test\u00e9s et qu&#8217;ils soient essentiellement exp\u00e9rimentaux est pratiquement pass\u00e9 sous le radar au pays. Je me r\u00e9f\u00e8re \u00e0 une experte en la mati\u00e8re, la professeure Allison M. Macfarlane. Elle est en fait l&#8217;ancienne pr\u00e9sidente de la U.S. Nuclear Regulatory Commission et travaille actuellement \u00e0 l&#8217;Universit\u00e9 de la Colombie-Britannique. Elle a d\u00e9clar\u00e9 ceci \u00e0 la CBC: \u00ab Personne ne sait quels sont les chiffres, et quiconque vous donne des chiffres vous vend un pont qui ne m\u00e8ne nulle part, parce que cette personne ne sait pas. Personne n&#8217;a jamais mis en place un r\u00e9acteur \u00e0 sels fondus ni ne l&#8217;a utilis\u00e9 pour produire de l&#8217;\u00e9lectricit\u00e9. \u00bb<\/p>\n<p>Les gouvernements du Canada et du Nouveau-Brunswick investissent justement des dizaines de millions de dollars dans un r\u00e9acteur \u00e0 sels fondus. Un exploitant du secteur priv\u00e9 a propos\u00e9 ce type de r\u00e9acteur et souhaite obtenir l&#8217;autorisation d&#8217;en construire. On examine la question en ce moment, mais on investit de l&#8217;argent dans un r\u00e9acteur \u00e0 sels fondus qui utilisera du plutonium provenant du combustible \u00e9puis\u00e9 de la centrale de Point Lepreau. Il s&#8217;agit d&#8217;une technologie non \u00e9prouv\u00e9e qui devrait permettre de produire de l&#8217;\u00e9lectricit\u00e9.<\/p>\n<p>Tout cela reste \u00e0 prouver, \u00e0 l&#8217;exception d&#8217;une chose. Utiliser du plutonium provenant de combustible \u00e9puis\u00e9 pose un \u00e9norme risque, le genre de risque contre lesquels les trait\u00e9s de non-prolif\u00e9ration des armes nucl\u00e9aires s&#8217;efforcent de nous prot\u00e9ger. Dans une \u00e9conomie mondiale fond\u00e9e sur le plutonium, m\u00eame une minuscule, une infinit\u00e9simale quantit\u00e9 de plutonium qui se retrouverait entre les mains de terroristes pourrait servir \u00e0 fabriquer une bombe sale. Et entre les mains d&#8217;autres pays, il y a fort \u00e0 parier que ce plutonium serve \u00e0 fabriquer une arme nucl\u00e9aire.<\/p>\n<p>Cela a \u00e9t\u00e9 le cas en 1974, lorsque le Canada a donn\u00e9 un de ses r\u00e9acteurs CANDU \u00e0 l&#8217;Inde. On a justement pu lire plus t\u00f4t cette semaine dans le Globe and Mail que ces petits r\u00e9acteurs modulaires produisent beaucoup plus de d\u00e9chets radioactifs \u2014 entre 2 et 30 fois \u2014 que les r\u00e9acteurs classiques.<\/p>\n<p>Je demande au gouvernement d&#8217;y songer \u00e0 deux fois. C&#8217;est une erreur. C&#8217;est un rem\u00e8de de charlatan radioactif.<\/p>","protected":false},"excerpt":{"rendered":"<p>Elizabeth May (Saanich\u2014Gulf Islands) 2022-06-07 23:31 [p.6306] Monsieur le Pr\u00e9sident, je suis heureuse de prendre la parole aujourd&#8217;hui dans le cadre du d\u00e9bat d&#8217;ajournement. Je dois dire que&hellip;<\/p>\n","protected":false},"author":1381,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[20,15],"tags":[573,2639,2692],"class_list":["post-26497","post","type-post","status-publish","format-standard","hentry","category-debate","category-parliament","tag-climate-crisis","tag-nuclear","tag-smr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les PRM ne font pas partie d&#039;aucune solution \u00e0 la crise climatique | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les PRM ne font pas partie d&#039;aucune solution \u00e0 la crise climatique | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Elizabeth May (Saanich\u2014Gulf Islands) 2022-06-07 23:31 [p.6306] Monsieur le Pr\u00e9sident, je suis heureuse de prendre la parole aujourd&#8217;hui dans le cadre du d\u00e9bat d&#8217;ajournement. Je dois dire que&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-08T06:31:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-16T14:18:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/Capture-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"578\" \/>\n\t<meta property=\"og:image:height\" content=\"323\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elizabeth May\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elizabeth May\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\\\/\"},\"author\":{\"name\":\"Elizabeth May\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/8ad70c936dfbb0f3a3af6907c5fdd64c\"},\"headline\":\"Les PRM ne font pas partie d&#8217;aucune solution \u00e0 la crise climatique\",\"datePublished\":\"2022-06-08T06:31:52+00:00\",\"dateModified\":\"2022-06-16T14:18:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\\\/\"},\"wordCount\":1496,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"keywords\":[\"Climate Crisis\",\"Nuclear\",\"SMR\"],\"articleSection\":[\"D\u00e9bat\",\"Parlement\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\\\/\",\"name\":\"Les PRM ne font pas partie d'aucune solution \u00e0 la crise climatique | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2022-06-08T06:31:52+00:00\",\"dateModified\":\"2022-06-16T14:18:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Small Modular Reactors&#8221; are not part of a solution to the climate crisis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/8ad70c936dfbb0f3a3af6907c5fdd64c\",\"name\":\"Elizabeth May\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g\",\"caption\":\"Elizabeth May\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/outreach-coordinator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les PRM ne font pas partie d'aucune solution \u00e0 la crise climatique | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/","og_locale":"en_US","og_type":"article","og_title":"Les PRM ne font pas partie d'aucune solution \u00e0 la crise climatique | Elizabeth May","og_description":"Elizabeth May (Saanich\u2014Gulf Islands) 2022-06-07 23:31 [p.6306] Monsieur le Pr\u00e9sident, je suis heureuse de prendre la parole aujourd&#8217;hui dans le cadre du d\u00e9bat d&#8217;ajournement. Je dois dire que&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2022-06-08T06:31:52+00:00","article_modified_time":"2022-06-16T14:18:19+00:00","og_image":[{"width":578,"height":323,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/Capture-3.jpg","type":"image\/jpeg"}],"author":"Elizabeth May","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Elizabeth May","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/"},"author":{"name":"Elizabeth May","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/8ad70c936dfbb0f3a3af6907c5fdd64c"},"headline":"Les PRM ne font pas partie d&#8217;aucune solution \u00e0 la crise climatique","datePublished":"2022-06-08T06:31:52+00:00","dateModified":"2022-06-16T14:18:19+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/"},"wordCount":1496,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"keywords":["Climate Crisis","Nuclear","SMR"],"articleSection":["D\u00e9bat","Parlement"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/","url":"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/","name":"Les PRM ne font pas partie d'aucune solution \u00e0 la crise climatique | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2022-06-08T06:31:52+00:00","dateModified":"2022-06-16T14:18:19+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/small-modular-reactors-are-not-part-of-a-solution-to-the-climate-crisis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"&#8220;Small Modular Reactors&#8221; are not part of a solution to the climate crisis"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/8ad70c936dfbb0f3a3af6907c5fdd64c","name":"Elizabeth May","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f32b0419a16ab6a875eb96521d826f03c3f2e604de2976ea8bf5afa253f814a?s=96&d=mm&r=g","caption":"Elizabeth May"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/outreach-coordinator\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/26497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/1381"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=26497"}],"version-history":[{"count":1,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/26497\/revisions"}],"predecessor-version":[{"id":26498,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/26497\/revisions\/26498"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=26497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=26497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=26497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}