{"id":3085,"date":"2012-02-15T10:36:53","date_gmt":"2012-02-15T15:36:53","guid":{"rendered":"http:\/\/elizabethmaymp.ca?p=3085"},"modified":"2012-02-16T10:51:40","modified_gmt":"2012-02-16T15:51:40","slug":"foreign-investment-a","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/","title":{"rendered":"Les investissements \u00e9trangers (A)"},"content":{"rendered":"<p><strong>Elizabeth May :<\/strong> Madame la Pr\u00e9sidente, je veux revenir sur un point qui a \u00e9t\u00e9 soulev\u00e9 \u00e0 la p\u00e9riode des questions. J&#8217;aimerais examiner un certain nombre d&#8217;investissements qui ont \u00e9t\u00e9 effectu\u00e9s, plus particuli\u00e8rement en lien avec le r\u00e9cent voyage du premier ministre en Chine. On nous a dit que d&#8217;\u00e9normes progr\u00e8s ont \u00e9t\u00e9 r\u00e9alis\u00e9s pour l&#8217;\u00e9conomie canadienne. Je pense que de nombreux Canadiens ont des questions \u00e0 poser maintenant que nous enregistrons une hausse substantielle des investissements directs d\u00e9coulant d&#8217;accords commerciaux conclus avec des conseils d&#8217;administration contr\u00f4l\u00e9s par le Parti communiste chinois, ce qui signifie la main-mise d&#8217;entreprises appartenant au gouvernement de la Chine sur des ressources canadiennes.<\/p>\n<p>Je tiens \u00e0 pr\u00e9ciser que j&#8217;appuie l&#8217;id\u00e9e de consolider nos liens avec la Chine. Je ne parle pas de nos rapports avec la Chine ni de l&#8217;importance de soulever la question des droits de la personne au Tibet ni du sort des dissidents d\u00e9tenus dans les prisons chinoises. Les occasions de soulever ces questions se multiplient lorsque nous entretenons des relations solides et respectueuses. Je parle des mesures que les Canadiens devraient prendre pour s&#8217;assurer que les examens des investissements \u00e9trangers sont clairs, que l&#8217;information est transparente et disponible et que des examens de la s\u00e9curit\u00e9 nationale sont \u00e9galement effectu\u00e9s, surtout lorsqu&#8217;on vend des ressources canadiennes strat\u00e9giques, comme les sables p\u00e9trolif\u00e8res et l&#8217;uranium, \u00e0 des entreprises de la R\u00e9publique populaire de Chine.<\/p>\n<p>J\u2019aimerais mettre cela en contexte. Le ministre des Ressources naturelles a dit qu\u2019il y avait peu d\u2019investissements directs de la Chine dans l\u2019exploitation des sables bitumineux. Sur les 73,6 milliards de dollars investis dans ce secteur entre 2007 et 2011, l\u2019investissement de la Chine repr\u00e9sente environ 12 milliards de dollars, soit 16 p. 100 du total. Ce n\u2019est pas un petit pourcentage.<\/p>\n<p>La participation d\u2019entreprises chinoises, plus particuli\u00e8rement de PetroChina, de la China National Offshore Oil Corporation et, surtout de Sinopec, a une dimension strat\u00e9gique. Sinopec a r\u00e9ussi \u00e0 acqu\u00e9rir une part de 9 p. 100 dans Syncrude pour environ 5 milliards de dollars. Elle a r\u00e9ussi \u00e0 obtenir un si\u00e8ge au conseil de Syncrude et le droit de v\u00e9to pour toute d\u00e9cision que Syncrude pourrait prendre pour que le bitume brut soit transform\u00e9 au Canada, ce qui se traduirait par la cr\u00e9ation d\u2019emplois canadiens dans des raffineries canadiennes. Cet avantage strat\u00e9gique de Sinopec ne semble pas avoir \u00e9t\u00e9 \u00e9tudi\u00e9 de la fa\u00e7on dont les Canadiens s&#8217;y seraient attendu.\u00a0<\/p>\n<p>Lorsque j\u2019ai pos\u00e9 cette question au sujet des sables bitumineux la semaine derni\u00e8re, le ministre de l&#8217;Industrie a all\u00e9gu\u00e9 qu\u2019en 2009, \u00ab nous avons am\u00e9lior\u00e9 la transparence \u00bb, en r\u00e9ponse \u00e0 ma question au sujet des consid\u00e9rations li\u00e9es \u00e0 la s\u00e9curit\u00e9 nationale de ce type d\u2019investissement. En fait, si nous regardons les d\u00e9cisions prises en 2009, nous constatons que le Cabinet a rejet\u00e9 l\u2019avis du Groupe d&#8217;\u00e9tude sur les politiques en mati\u00e8re de concurrence cr\u00e9\u00e9 en 2007. Le Groupe d&#8217;\u00e9tude avait pour mandat d\u2019examiner ces accords.<\/p>\n<p>Selon la Gazette du Canada du 30 septembre 2009:<\/p>\n<p style=\"padding-left: 30px;\"><em>L\u2019expression s\u00e9curit\u00e9 nationale devrait \u00eatre d\u00e9finie explicitement et les examens en fonction de la s\u00e9curit\u00e9 nationale devraient \u00eatre effectu\u00e9s en fonction de crit\u00e8res concrets, objectifs et transparents. Cette recommandation n\u2019a pas \u00e9t\u00e9 accept\u00e9e [\u2026]. <\/em><\/p>\n<p>En plus de l\u2019investissement dans l\u2019exploitation des sables bitumineux, voil\u00e0 que le premier ministre nous revient avec une entente sur l\u2019uranium. Cette entente est assortie de proc\u00e9d\u00e9s comptables beaucoup plus laxistes que ceux qui avaient \u00e9t\u00e9 propos\u00e9s dans les ententes pr\u00e9c\u00e9dentes avec la Chine, proc\u00e9d\u00e9s qui avaient amen\u00e9 le Canada, par le pass\u00e9, \u00e0 cesser de vendre de l\u2019uranium en Chine. La pr\u00e9occupation strat\u00e9gique ne concerne pas uniquement l\u2019usage que ferait la Chine de l\u2019uranium, mais aussi la relation qu&#8217;entretient le pays avec le Pakistan dans le cadre du programme nucl\u00e9aire civile de ce dernier et le risque de prolif\u00e9ration nucl\u00e9aire qui pourrait en r\u00e9sulter. Ce sont des pr\u00e9occupations d\u2019ordre strat\u00e9gique.<\/p>\n<p>J\u2019aimerais que le gouvernement dise aux Canadiens exactement quel examen en fonction de la s\u00e9curit\u00e9 nationale\u2026<\/p>\n<p><strong>La vice-pr\u00e9sidente : <\/strong>\u00c0 l&#8217;ordre, s&#8217;il vous pla\u00eet.<\/p>\n<p>Le secr\u00e9taire parlementaire du ministre de l&#8217;Industrie a la parole.<\/p>\n<p><strong>Mike Lake : <\/strong>Madame la Pr\u00e9sidente, j&#8217;ai pris note des questions que la d\u00e9put\u00e9e a pos\u00e9es la semaine derni\u00e8re et cette semaine encore. Les deux questions sont importantes vu le d\u00e9bat qui se tient ce soir.<\/p>\n<p>La semaine derni\u00e8re elle a pos\u00e9 une question au ministre concernant les dispositions touchant la s\u00e9curit\u00e9 nationale dans la Loi sur Investissement Canada. Le ministre lui a r\u00e9pondu que ces dispositions avaient \u00e9t\u00e9 ajout\u00e9es \u00e0 la loi en 2009. La d\u00e9put\u00e9e de Saanich\u2014Gulf Islands n&#8217;a pas \u00e9t\u00e9 satisfaite de cette r\u00e9ponse et elle lui a pos\u00e9 la question suivante hier:<\/p>\n<p style=\"padding-left: 30px;\"><em>Monsieur le Pr\u00e9sident, la semaine derni\u00e8re, j&#8217;ai pos\u00e9 une question au ministre de l&#8217;Industrie concernant la mainmise de la Chine sur les ressources canadiennes. <\/em><\/p>\n<p style=\"padding-left: 30px;\"><em>Il a dit que je ne connaissais pas bien les modifications qui ont \u00e9t\u00e9 apport\u00e9es en 2009 \u00e0 la Loi sur Investissement Canada. <\/em><\/p>\n<p>Elle a ensuite ajout\u00e9 ceci:<\/p>\n<p style=\"padding-left: 30px;\"><em>En fait, on pouvait lire ce qui suit dans le num\u00e9ro du 30 septembre de 2009 de la Gazette du Canada:\u00a0 <\/em><\/p>\n<p>Elle a par la suite cit\u00e9 la Gazette du Canada, comme elle vient tout juste de le faire:<\/p>\n<p style=\"padding-left: 30px;\"><em>L&#8217;expression s\u00e9curit\u00e9 nationale devrait \u00eatre d\u00e9finie explicitement et les examens en fonction de la s\u00e9curit\u00e9 nationale devraient \u00eatre effectu\u00e9s en fonction de crit\u00e8res concrets, objectifs et transparents. Cette recommandation n&#8217;a pas \u00e9t\u00e9 accept\u00e9e [&#8230;]\u00a0 <\/em><\/p>\n<p>Puis la d\u00e9put\u00e9e a dit aujourd&#8217;hui \u00ab fin de la citation \u00bb.<\/p>\n<p>Le probl\u00e8me, c&#8217;est que le passage tir\u00e9 de la Gazette du Canada ne finit pas l\u00e0. La phrase continue. La d\u00e9put\u00e9e de Saanich\u2014Gulf Islands a commis deux erreurs. D&#8217;abord, le passage qu&#8217;elle a cit\u00e9 provient d&#8217;un recueil des commentaires et r\u00e9ponses concernant la publication, dans la Gazette, de dispositions sur la s\u00e9curit\u00e9 nationale \u00e0 l&#8217;\u00e9t\u00e9 2009. Elle n&#8217;a pas cit\u00e9 le r\u00e8glement lui-m\u00eame. Ensuite, elle a tronqu\u00e9 la citation, comme je viens de le mentionner.<\/p>\n<p>La citation int\u00e9grale tir\u00e9e des commentaires et r\u00e9ponses est la suivante. Le passage suivant provient de la Gazette du Canada:<\/p>\n<p style=\"padding-left: 30px;\">\u00a0(<em>4) L\u2019expression s\u00e9curit\u00e9 nationale devrait \u00eatre d\u00e9finie explicitement et les examens en fonction de la s\u00e9curit\u00e9 nationale devraient \u00eatre effectu\u00e9s en fonction de crit\u00e8res concrets, objectifs et transparents. Cette recommandation n\u2019a pas \u00e9t\u00e9 accept\u00e9e en raison de la nature dynamique des menaces \u00e0 la s\u00e9curit\u00e9 nationale et de leur constante \u00e9volution. Ni la Partie IV.1 de la LIC, ni le R\u00e8glement ne d\u00e9finissent l\u2019expression \u00ab s\u00e9curit\u00e9 nationale \u00bb puisque les futures menaces relatives \u00e0 la s\u00e9curit\u00e9 nationale ne peuvent \u00eatre pr\u00e9d\u00e9termin\u00e9es et qu\u2019une telle d\u00e9finition pourrait r\u00e9duire la capacit\u00e9 du gouvernement de r\u00e9agir \u00e0 de futures menaces. <\/em><\/p>\n<p>Voil\u00e0 la citation int\u00e9grale.<\/p>\n<p>Cela ne signifie pas pour autant qu&#8217;il n&#8217;existe aucune disposition sur la s\u00e9curit\u00e9 nationale. Comment je le sais? Parce qu&#8217;elles sont faciles \u00e0 trouver. Il suffit de prendre son BlackBerry ou son iPad et d&#8217;aller \u00e0 <a href=\"http:\/\/www.ic.gc.ca\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.ic.gc.ca<\/a>. Apr\u00e8s la s\u00e9ance, je pourrais montrer le site \u00e0 la d\u00e9put\u00e9e sur mon iPad si elle le d\u00e9sire. Cela fait plus de deux ans que les dispositions ont \u00e9t\u00e9 publi\u00e9es. J&#8217;invite la d\u00e9put\u00e9e \u00e0 lire cette section du site web et le r\u00e8glement connexe avant de poser une nouvelle question maladroite.<\/p>","protected":false},"excerpt":{"rendered":"<p>Elizabeth May : Madame la Pr\u00e9sidente, je veux revenir sur un point qui a \u00e9t\u00e9 soulev\u00e9 \u00e0 la p\u00e9riode des questions. J&#8217;aimerais examiner un certain nombre d&#8217;investissements qui&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[20],"tags":[98,45,571,617,31,13,449,89,520,530,529,97,140,618],"class_list":["post-3085","post","type-post","status-publish","format-standard","hentry","category-debate","tag-china","tag-economy","tag-foreign-investment","tag-hunan-rights","tag-international-affairs","tag-justice","tag-national-security","tag-oil-sands","tag-pakistan","tag-petrochina","tag-sinopec","tag-tibet","tag-trade","tag-uranium"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les investissements \u00e9trangers (A) | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les investissements \u00e9trangers (A) | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Elizabeth May : Madame la Pr\u00e9sidente, je veux revenir sur un point qui a \u00e9t\u00e9 soulev\u00e9 \u00e0 la p\u00e9riode des questions. J&#8217;aimerais examiner un certain nombre d&#8217;investissements qui&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-15T15:36:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-02-16T15:51:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Craig Cantin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Craig Cantin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/foreign-investment-a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/foreign-investment-a\\\/\"},\"author\":{\"name\":\"Craig Cantin\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\"},\"headline\":\"Les investissements \u00e9trangers (A)\",\"datePublished\":\"2012-02-15T15:36:53+00:00\",\"dateModified\":\"2012-02-16T15:51:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/foreign-investment-a\\\/\"},\"wordCount\":2408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"keywords\":[\"la Chine\",\"\u00c9conomie\",\"Foreign Investment\",\"Hunan Rights\",\"Affaires \u00e9trang\u00e8res\",\"Justice\",\"National Security\",\"Sables bitumineux\",\"Pakistan\",\"PetroChina\",\"Sinopec\",\"le Tibet\",\"Commerce\",\"Uranium\"],\"articleSection\":[\"D\u00e9bat\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/foreign-investment-a\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/foreign-investment-a\\\/\",\"name\":\"Foreign Investment (A)Les investissements \u00e9trangers (A) | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2012-02-15T15:36:53+00:00\",\"dateModified\":\"2012-02-16T15:51:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/foreign-investment-a\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/foreign-investment-a\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/foreign-investment-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foreign Investment (A)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\",\"name\":\"Craig Cantin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"caption\":\"Craig Cantin\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/craig-c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les investissements \u00e9trangers (A) | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/","og_locale":"en_US","og_type":"article","og_title":"Les investissements \u00e9trangers (A) | Elizabeth May","og_description":"Elizabeth May : Madame la Pr\u00e9sidente, je veux revenir sur un point qui a \u00e9t\u00e9 soulev\u00e9 \u00e0 la p\u00e9riode des questions. J&#8217;aimerais examiner un certain nombre d&#8217;investissements qui&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2012-02-15T15:36:53+00:00","article_modified_time":"2012-02-16T15:51:40+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Craig Cantin","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Craig Cantin","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/foreign-investment-a\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/foreign-investment-a\/"},"author":{"name":"Craig Cantin","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f"},"headline":"Les investissements \u00e9trangers (A)","datePublished":"2012-02-15T15:36:53+00:00","dateModified":"2012-02-16T15:51:40+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/foreign-investment-a\/"},"wordCount":2408,"commentCount":0,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"keywords":["la Chine","\u00c9conomie","Foreign Investment","Hunan Rights","Affaires \u00e9trang\u00e8res","Justice","National Security","Sables bitumineux","Pakistan","PetroChina","Sinopec","le Tibet","Commerce","Uranium"],"articleSection":["D\u00e9bat"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/","url":"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/","name":"Foreign Investment (A)Les investissements \u00e9trangers (A) | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2012-02-15T15:36:53+00:00","dateModified":"2012-02-16T15:51:40+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/foreign-investment-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Foreign Investment (A)"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f","name":"Craig Cantin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","caption":"Craig Cantin"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/craig-c\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/3085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=3085"}],"version-history":[{"count":2,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/3085\/revisions"}],"predecessor-version":[{"id":3260,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/3085\/revisions\/3260"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=3085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=3085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=3085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}