{"id":419,"date":"2011-09-22T15:09:23","date_gmt":"2011-09-22T15:09:23","guid":{"rendered":"http:\/\/dev.elizabethmaymp.ca\/?p=419"},"modified":"2014-09-26T08:43:26","modified_gmt":"2014-09-26T12:43:26","slug":"safe-streets-and-communities-act-c","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/","title":{"rendered":"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s"},"content":{"rendered":"<p><strong>Elizabeth May :<\/strong> Monsieur le Pr\u00e9sident, je remercie ma coll\u00e8gue de sa description tr\u00e8s juste, claire et coh\u00e9rente des probl\u00e8mes que pose, \u00e0 mon avis, le projet de loi C-10 \u00e0 tous les d\u00e9put\u00e9s de l&#8217;opposition.<\/p>\n<p>J&#8217;aurais aim\u00e9 poser cette question \u00e0 un minist\u00e9riel, mais je n&#8217;en ai pas eu l&#8217;occasion dans cette s\u00e9rie de questions. Le fait que la quasi-totalit\u00e9 des criminologues et experts qui ont examin\u00e9 la question des peines minimales obligatoires ont conclu que celles-ci sont inefficaces me laisse perplexe. En fait, un article r\u00e9cemment publi\u00e9 dans Criminology &#038; Public Policy commence par la phrase suivante:<\/p>\n<p>Les peines minimales obligatoires sont un cas classique o\u00f9 l&#8217;approche adopt\u00e9e sur le plan de la criminologie diverge de celle adopt\u00e9e sur le plan de la politique publique.<\/p>\n<p>Tous les d\u00e9put\u00e9s veulent mettre fin \u00e0 la criminalit\u00e9 et prot\u00e9ger les victimes.<\/p>\n<p>J&#8217;aimerais que le d\u00e9put\u00e9 me dise si l&#8217;approche adopt\u00e9e par le gouvernement a pu \u00eatre corrobor\u00e9e par des experts.<\/p>\n<p><strong>Guy Caron : <\/strong>Monsieur le Pr\u00e9sident, je remercie mon honorable coll\u00e8gue de sa question.<\/p>\n<p>Il n&#8217;y a absolument aucune preuve \u00e0 cet \u00e9gard, que ce soit du c\u00f4t\u00e9 des criminologues, des sociologues, du c\u00f4t\u00e9 acad\u00e9mique ou de toutes les personnes qui se pr\u00e9occupent de cette question. Il n&#8217;y a pas une seule \u00e9tude, qu&#8217;elle soit canadienne ou am\u00e9ricaine, qui d\u00e9montre la validit\u00e9 de l&#8217;approche que pr\u00e9conise pr\u00e9sentement le gouvernement. Aucune de ces \u00e9tudes ne d\u00e9montre qu&#8217;il existe un quelconque effet de dissuasion par l&#8217;adoption de peines minimales plus fortes. On s&#8217;en aper\u00e7oit particuli\u00e8rement aux \u00c9tats-Unis, mais aussi au Canada. Une telle approche va co\u00fbter des sommes qu&#8217;on ne conna\u00eet pas encore, mais on sait qu&#8217;elles seront \u00e9lev\u00e9es. Quant \u00e0 r\u00e9duire la criminalit\u00e9 et les co\u00fbts associ\u00e9s aux victimes, il n&#8217;y aura pas un seul impact. C&#8217;est la raison pour laquelle ce projet de loi ne peut pas \u00eatre acceptable.<\/p>\n<p>Si le gouvernement avait \u00e9t\u00e9 responsable, il aurait divis\u00e9 son projet de loi. Cela aurait permis \u00e0 l&#8217;opposition d&#8217;appuyer certains \u00e9l\u00e9ments qui auraient pu \u00eatre int\u00e9ressants et faire l&#8217;objet d&#8217;un consensus, comme on a travaill\u00e9 ensemble pour les m\u00e9gaproc\u00e8s au mois de juin. Mais dans ce cas-ci, c&#8217;est impossible.<\/p>","protected":false},"excerpt":{"rendered":"<p>Elizabeth May : Monsieur le Pr\u00e9sident, je remercie ma coll\u00e8gue de sa description tr\u00e8s juste, claire et coh\u00e9rente des probl\u00e8mes que pose, \u00e0 mon avis, le projet de&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[20],"tags":[13,64],"class_list":["post-419","post","type-post","status-publish","format-standard","hentry","category-debate","tag-justice","tag-minimum-mandatory-sentences"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Elizabeth May : Monsieur le Pr\u00e9sident, je remercie ma coll\u00e8gue de sa description tr\u00e8s juste, claire et coh\u00e9rente des probl\u00e8mes que pose, \u00e0 mon avis, le projet de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-22T15:09:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-09-26T12:43:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Craig Cantin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Craig Cantin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/safe-streets-and-communities-act-c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/safe-streets-and-communities-act-c\\\/\"},\"author\":{\"name\":\"Craig Cantin\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\"},\"headline\":\"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s\",\"datePublished\":\"2011-09-22T15:09:23+00:00\",\"dateModified\":\"2014-09-26T12:43:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/safe-streets-and-communities-act-c\\\/\"},\"wordCount\":750,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"keywords\":[\"Justice\",\"Peines minimales d'emprisonnement\"],\"articleSection\":[\"D\u00e9bat\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-c\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-c\\\/\",\"name\":\"Safe Streets and Communities ActLoi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2011-09-22T15:09:23+00:00\",\"dateModified\":\"2014-09-26T12:43:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-c\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-c\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/safe-streets-and-communities-act-c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Safe Streets and Communities Act\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\",\"name\":\"Craig Cantin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"caption\":\"Craig Cantin\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/craig-c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/","og_locale":"en_US","og_type":"article","og_title":"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s | Elizabeth May","og_description":"Elizabeth May : Monsieur le Pr\u00e9sident, je remercie ma coll\u00e8gue de sa description tr\u00e8s juste, claire et coh\u00e9rente des probl\u00e8mes que pose, \u00e0 mon avis, le projet de&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2011-09-22T15:09:23+00:00","article_modified_time":"2014-09-26T12:43:26+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Craig Cantin","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Craig Cantin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/safe-streets-and-communities-act-c\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/safe-streets-and-communities-act-c\/"},"author":{"name":"Craig Cantin","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f"},"headline":"Loi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s","datePublished":"2011-09-22T15:09:23+00:00","dateModified":"2014-09-26T12:43:26+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/safe-streets-and-communities-act-c\/"},"wordCount":750,"commentCount":0,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"keywords":["Justice","Peines minimales d'emprisonnement"],"articleSection":["D\u00e9bat"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/","url":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/","name":"Safe Streets and Communities ActLoi sur la s\u00e9curit\u00e9 des rues et des communaut\u00e9s | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2011-09-22T15:09:23+00:00","dateModified":"2014-09-26T12:43:26+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/safe-streets-and-communities-act-c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Safe Streets and Communities Act"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f","name":"Craig Cantin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","caption":"Craig Cantin"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/craig-c\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=419"}],"version-history":[{"count":3,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/419\/revisions"}],"predecessor-version":[{"id":967,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/419\/revisions\/967"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}