{"id":7713,"date":"2012-11-28T17:02:22","date_gmt":"2012-11-28T22:02:22","guid":{"rendered":"http:\/\/elizabethmaymp.ca?p=7713"},"modified":"2012-11-28T17:56:43","modified_gmt":"2012-11-28T22:56:43","slug":"amendments-to-bill-c-45","status":"publish","type":"post","link":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/","title":{"rendered":"Les amendements au projet de loi C-45"},"content":{"rendered":"<p><em>Projet de loi C-45 : Loi no 2 portant ex\u00e9cution de certaines dispositions du budget d\u00e9pos\u00e9 au Parlement le 29 mars 2012 et mettant en oeuvre d&#8217;autres mesures <\/em><\/p>\n<p><strong>Motion no 28 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 9, soit modifi\u00e9 par suppression des lignes 13 et 14, page 14.<\/p>\n<p><strong>Motion no 29 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 9, soit modifi\u00e9 par substitution, \u00e0 la ligne 3, page 15, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab avant 2020, \u00bb<\/p>\n<p><strong>Motion no 74 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 27, soit modifi\u00e9 par substitution, \u00e0 la ligne 19, page 35, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab a.1) 19.98 % de l\u2019exc\u00e9dent du compte de \u00bb<\/p>\n<p><strong>Motion no 239 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 175, soit modifi\u00e9 par substitution, aux lignes 27 \u00e0 32, page 204, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab une organisation autochtone ou ses membres en vertu d&#8217;un trait\u00e9 ou d&#8217;un accord sur des revendications territoriales ou, en conformit\u00e9 avec le droit inh\u00e9rent des Autochtones, la p\u00eache pratiqu\u00e9e par une organisation autochtone ou ses membres en vue d&#8217;une utilisation traditionnelle, notamment \u00e0 des fins de consommation personnelle ou \u00e0 des fins sociales ou c\u00e9r\u00e9moniales. \u00bb<\/p>\n<p><strong>Motion no 249 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 179, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 9, page 208, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (3) Les exemptions pr\u00e9vues au paragraphe (1) ne s&#8217;appliquent que si la personne qui se propose de construire le pont, la promenade ou un ouvrage connexe d\u00e9montre que l&#8217;exploitation de tout ouvrage ou entreprise ou l&#8217;exercice de toute activit\u00e9 aux fins de construction du pont, de la promenade ou de l&#8217;ouvrage connexe :<\/p>\n<p style=\"padding-left: 30px;\">a) ne fera pas obstacle \u00e0 la navigation;<\/p>\n<p style=\"padding-left: 30px;\">b) ne causera pas la destruction du poisson ou la d\u00e9t\u00e9rioration, la destruction ou la perturbation de l&#8217;habitat du poisson au sens de la Loi sur les p\u00eaches;<\/p>\n<p style=\"padding-left: 30px;\">c) ne mettra pas en p\u00e9ril la survie ou le r\u00e9tablissement de toute esp\u00e8ce prot\u00e9g\u00e9e au titre de la Loi sur les esp\u00e8ces en p\u00e9ril. \u00bb<\/p>\n<p><strong>Motion no 250 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 179, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 19, page 208, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (3) L&#8217;exemption pr\u00e9vue au paragraphe (1) ne s&#8217;applique que si la personne qui se propose de construire le pont, la promenade ou un ouvrage connexe d\u00e9montre \u2014 quant \u00e0 l&#8217;exploitation de tout ouvrage ou entreprise ou \u00e0 l&#8217;exercice de toute activit\u00e9 aux fins de construction du pont, de la promenade ou de l&#8217;ouvrage connexe \u2014 que la construction n&#8217;entra\u00eenera pas d&#8217;effet nuisible sur l&#8217;environnement. \u00bb<\/p>\n<p><strong>Motion no 341 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 266, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 7, page 260, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (9) Il est entendu que les renseignements r\u00e9glementaires fournis \u00e0 l&#8217;Agence au sujet des personnes qui sont ou devraient \u00eatre \u00e0 bord d&#8217;un moyen de transport sont assujettis \u00e0 la Loi sur la protection des renseignements personnels. \u00bb<\/p>\n<p><strong>Motion no 342 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 266, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 7, page 260, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab 12.2 Dans les six mois suivant la date d\u2019entr\u00e9e en vigueur des r\u00e8glements pris au titre du paragraphe 12.1(8), il est proc\u00e9d\u00e9 \u00e0 une \u00e9valuation des effets de l&#8217;article 12.1 et de ces r\u00e8glements sur le droit \u00e0 la vie priv\u00e9e et il en est fait rapport \u00e0 chaque chambre du Parlement. \u00bb<\/p>\n<p><strong>Motion no 351 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 274, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 33, page 262, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (3) Dans les quatre premiers mois de chaque ann\u00e9e, le bureau pr\u00e9sente au ministre un rapport de ses activit\u00e9s au cours de l&#8217;ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<p style=\"padding-left: 30px;\">(4) Le ministre fait d\u00e9poser un exemplaire du rapport devant chaque chambre du Parlement dans un d\u00e9lai de quinze jours de s\u00e9ance suivant sa r\u00e9ception.<\/p>\n<p style=\"padding-left: 30px;\">(5) Le ministre envoie au lieutenant-gouverneur de chaque province un exemplaire du rapport d\u00e8s le d\u00e9p\u00f4t de celui-ci devant les deux chambres.<\/p>\n<p style=\"padding-left: 30px;\">(6) Pour l\u2019application du pr\u00e9sent article, \u00ab jour de s\u00e9ance \u00bb s\u2019entend d\u2019un jour o\u00f9 l\u2019une ou l\u2019autre chambre du Parlement si\u00e8ge. \u00bb<\/p>\n<p><strong>Motion no 352 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 275.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 353 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 276.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 360 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 279, soit modifi\u00e9 :<\/p>\n<p style=\"padding-left: 30px;\">a) par substitution, \u00e0 la ligne 7, page 265, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab 47. (1) Le ministre peut, apr\u00e8s consultation du public, d\u00e9signer tout indi- \u00bb<\/p>\n<p style=\"padding-left: 30px;\">b) par substitution, aux lignes 12 \u00e0 18, page 265, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab pouvoirs et fonctions relatifs au contr\u00f4le des demandes de \u00bb<\/p>\n<p><strong>Motion no 381 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 302, soit modifi\u00e9 par substitution, \u00e0 la ligne 4, page 271, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab 9. (1) Sauf dans les cas o\u00f9 une province agit dans l&#8217;un des objectifs l\u00e9gitimes mentionn\u00e9s \u00e0 l&#8217;article 404 de l&#8217;Accord \u2014 \u00e0 savoir la s\u00e9curit\u00e9 du public, l&#8217;ordre public, la protection de la vie ou de la sant\u00e9 des humains, des animaux ou des v\u00e9g\u00e9taux, la protection de l&#8217;environnement, la protection des consommateurs, la protection de la sant\u00e9, de la s\u00e9curit\u00e9 et du bien-\u00eatre des travailleurs et les programmes de promotion sociale \u00e0 l&#8217;intention des groupes d\u00e9favoris\u00e9s \u2014 le gouverneur en conseil peut, par \u00bb<\/p>\n<p><strong>Motion no 383 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 307, soit modifi\u00e9 :<\/p>\n<p style=\"padding-left: 30px;\">a) par substitution, aux lignes 4 et 5, page 272, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (8.91) Lorsqu&#8217;une cotisation patronale est de 10 000 $ ou moins :<\/p>\n<p style=\"padding-left: 30px;\">a) pour 2011, le ministre<\/p>\n<p style=\"padding-left: 30px;\">b) par substitution, aux lignes 15 et 16, page 272, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab b) pour 2012, le ministre rembourse \u00e0 l&#8217;employeur la partie de sa cotisation patronale pour 2013, calcul\u00e9e selon la formule ci-apr\u00e8s, qui exc\u00e8de 2 $ :<\/p>\n<p style=\"padding-left: 30px;\">C2 \u2013 C1<\/p>\n<p style=\"padding-left: 30px;\">o\u00f9 :<\/p>\n<p style=\"padding-left: 30px;\">C1 repr\u00e9sente le montant de la cotisation patronale pour 2012,<\/p>\n<p style=\"padding-left: 30px;\">C2 le montant de la cotisation patronale pour 2013;<\/p>\n<p style=\"padding-left: 30px;\">c) pour 2013, le ministre rembourse \u00e0 l&#8217;employeur la partie de sa cotisation patronale pour 2014, calcul\u00e9e selon la formule ci-apr\u00e8s, qui exc\u00e8de 2 $ :<\/p>\n<p style=\"padding-left: 30px;\">C2 \u2013 C1<\/p>\n<p style=\"padding-left: 30px;\">o\u00f9 :<\/p>\n<p style=\"padding-left: 30px;\">C1 repr\u00e9sente le montant de la cotisation patronale pour 2013,<\/p>\n<p style=\"padding-left: 30px;\">C2 le montant de la cotisation patronale pour 2014.<\/p>\n<p style=\"padding-left: 30px;\">(8.92) Pour l&#8217;application de l&#8217;alin\u00e9a (8.91)a), C1 est \u00e9gal \u00e0 z\u00e9ro dans les cas o\u00f9 une \u00bb<\/p>\n<p><strong>Motion no 384 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 307, soit modifi\u00e9 par substitution, \u00e0 la ligne 20, page 272, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab graphe (8.91) ne peut exc\u00e9der 2 000 $. \u00bb<\/p>\n<p><strong>Motion no 386 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 308, soit modifi\u00e9 par substitution, \u00e0 la ligne 31, page 272, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab dont il y a lieu de croire qu&#8217;il repr\u00e9sente une menace pr\u00e9cise et cr\u00e9dible pour la s\u00e9curit\u00e9 doit, pr\u00e9alablement \u00e0 son entr\u00e9e au Canada, \u00bb<\/p>\n<p><strong>Motion no 388 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 308, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 3, page 273, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (1.02) Le ministre fait d\u00e9poser tout projet de r\u00e8glement pris au titre du paragraphe (1.01) devant chaque chambre du Parlement; celle-ci renvoie le projet \u00e0 son comit\u00e9 comp\u00e9tent.<\/p>\n<p style=\"padding-left: 30px;\">(1.03) Le r\u00e8glement ne peut \u00eatre pris avant le premier en date des jours suivants :<\/p>\n<p style=\"padding-left: 30px;\">a) le trenti\u00e8me jour de s\u00e9ance suivant le d\u00e9p\u00f4t;<\/p>\n<p style=\"padding-left: 30px;\">b) le cent soixanti\u00e8me jour civil suivant le d\u00e9p\u00f4t;<\/p>\n<p style=\"padding-left: 30px;\">c) le lendemain du jour o\u00f9 les comit\u00e9s comp\u00e9tents auront tous deux pr\u00e9sent\u00e9 leur rapport.<\/p>\n<p style=\"padding-left: 30px;\">(1.04) Le ministre tient compte de tout rapport pr\u00e9sent\u00e9 par les comit\u00e9s. S\u2019il n\u2019est pas donn\u00e9 suite \u00e0 l\u2019une ou l\u2019autre des recommandations que contient un rapport, le ministre d\u00e9pose \u00e0 la chambre d\u2019o\u00f9 provient celui-ci une d\u00e9claration motiv\u00e9e \u00e0 cet \u00e9gard.<\/p>\n<p style=\"padding-left: 30px;\">(1.05) Il n\u2019est pas n\u00e9cessaire de d\u00e9poser de nouveau le projet de r\u00e8glement m\u00eame s\u2019il a subi des modifications. \u00bb<\/p>\n<p><strong>Motion no 389 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 308, soit modifi\u00e9 par substitution, \u00e0 la ligne 3,<\/p>\n<p style=\"padding-left: 30px;\">page 273, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab syst\u00e8me ou l\u2019agent peut d\u00e9livrer l\u2019autorisation et les renseignements personnels ne speuvent \u00eatre communiqu\u00e9s que conform\u00e9ment \u00e0 la Loi sur la protection des renseignements personnels. \u00bb<\/p>\n<p><strong>Motion no 390 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 308, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 3, page 273, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab (1.02) Aucune entreprise de s\u00e9curit\u00e9 priv\u00e9e ne peut participer \u00e0 la collecte, \u00e0 la diss\u00e9mination, \u00e0 la conservation ou \u00e0 l&#8217;\u00e9limination de renseignements personnels obtenus dans le cadre du syst\u00e8me d&#8217;autorisation \u00e9lectronique vis\u00e9 au paragraphe (1.01). \u00bb<\/p>\n<p><strong>Motion no 391 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 309.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 392 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 309, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 10, page 273, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (4) Dans les six mois suivant la date d&#8217;entr\u00e9e en vigueur des r\u00e8glements \u2014 relatifs aux autorisations de voyage \u00e9lectroniques \u2014 mentionn\u00e9s au paragraphe<\/p>\n<p style=\"padding-left: 30px;\">11(1.01), il est proc\u00e9d\u00e9 \u00e0 une \u00e9valuation des effets de ces autorisation sur le droit \u00e0 la vie priv\u00e9e et il en est fait rapport \u00e0 chaque chambre du Parlement. \u00bb<\/p>\n<p><strong>Motion no 393 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 309, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 10, page 273, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab (4) Les r\u00e8glements relatifs aux autorisations de voyage mentionn\u00e9s au paragraphe 11(1.01) ne peuvent \u00eatre pris qu&#8217;\u00e0 compter de deux ans apr\u00e8s l&#8217;entr\u00e9e en vigueur du pr\u00e9sent paragraphe afin de permettre la tenue de consultations avec l\u2019industrie du tourisme et d\u2019autres parties int\u00e9ress\u00e9es en vue d\u2019en \u00e9valuer les effets possibles sur l\u2019industrie. \u00bb<\/p>\n<p><strong>Motion no 395 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 311.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), M. Lamoureux (Winnipeg-Nord), M.<\/p>\n<p style=\"padding-left: 30px;\">Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p style=\"padding-left: 30px;\">Mme May (Saanich\u2014Gulf Islands) \u2014 27 Novembre 2012<\/p>\n<p><strong>Motion no 396 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 311, soit modifi\u00e9 par substitution, \u00e0 la ligne 21, page 273, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab aux paragraphes 11(1) et (1.01) \u2014 sauf \u00e0 celle dont l&#8217;autorisation est d\u00e9livr\u00e9e par le syst\u00e8me et \u00e0 celle \u00bb<\/p>\n<p><strong>Motion no 397 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 311, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 31, page 273, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab (1.01) Le pr\u00e9sent article cesse d&#8217;avoir effet en ce qui a trait aux autorisations de voyage \u00e9lectroniques vis\u00e9es au paragraphe 11(1.01), \u00e0 la fin du quinzi\u00e8me jour de s\u00e9ance post\u00e9rieur au 31 d\u00e9cembre 2016, sauf si, avant la fin de ce jour, il est prorog\u00e9 par r\u00e9solution adopt\u00e9e par les deux chambres du Parlement en faveur de son maintien. \u00bb<\/p>\n<p><strong>Motion no 398 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 312.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 401 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 313, soit modifi\u00e9 par suppression des lignes 16 \u00e0 27, page 274.<\/p>\n<p><strong>Motion no 409 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 317, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 24, page 277, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (7) L\u2019article 2 de la m\u00eame loi devient le paragraphe 2(1) et est modifi\u00e9 par adjonction de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">(2) Pour l&#8217;application de la pr\u00e9sente loi, afin de d\u00e9terminer si une d\u00e9cision est dans l&#8217;int\u00e9r\u00eat public, le ministre examine si elle aurait pour effet de prot\u00e9ger le droit de navigation du public ainsi que l&#8217;exercice de ce droit. \u00bb<\/p>\n<p><strong>Motion no 411 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, \u00e0 la ligne 31, page 277, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab ou sur, sous, au-dessus \u00bb<\/p>\n<p><strong>Motion no 412 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par suppression du passage commen\u00e7ant \u00e0 la ligne 35, page 277, et se terminant \u00e0 la ligne 17, page 278.<\/p>\n<p><strong>Motion no 413 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, \u00e0 la ligne 21, page 278, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab navigables ou sur, sous, \u00bb<\/p>\n<p><strong>Motion no 417 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 8, page 279, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab f) l&#8217;importance de ces eaux pour les peuples autochones dans leurs usages traditionnels et autres. \u00bb<\/p>\n<p><strong>Motion no 418 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 8, page 279, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab (4.1) Pour l\u2019application de la pr\u00e9sente loi, tout pont, estacade, barrage ou digue est r\u00e9put\u00e9 \u00eatre un ouvrage qui, de l&#8217;avis du ministre, risque de g\u00eaner s\u00e9rieusement la navigation. \u00bb<\/p>\n<p><strong>Motion no 421 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 37, page 279, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab (10) Tout ouvrage qui, selon la d\u00e9cision du ministre prise au titre du pr\u00e9sent article, risque de g\u00eaner s\u00e9rieusement la navigation est r\u00e9put\u00e9 \u00eatre une activit\u00e9 concr\u00e8te d\u00e9sign\u00e9e par r\u00e8glement pris en vertu de l&#8217;alin\u00e9a 84a) de la Loi canadienne sur l\u2019\u00e9valuation environnementale (2012) et li\u00e9e \u00e0 l\u2019Agence canadienne d\u2019\u00e9valuation environnementale. \u00bb<\/p>\n<p><strong>Motion no 422 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 8, page 280, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab (2.1) S&#8217;il n&#8217;a pas exig\u00e9 le d\u00e9p\u00f4t de renseignements et la publication d&#8217;un avis en vertu de l&#8217;alin\u00e9a 5(6)b), le ministre exige du propri\u00e9taire qu\u2019il d\u00e9pose les plans de l&#8217;ouvrage propos\u00e9, la description de l\u2019emplacement projet\u00e9 et tout autre renseignement que le ministre pr\u00e9cise au bureau d\u2019enregistrement ou au bureau des titres de bien-fonds du lieu en cause ou \u00e0 tout autre lieu qu\u2019il pr\u00e9cise et qu&#8217;il publie un avis contenant ces renseignements dans la Gazette du Canada et dans deux journaux publi\u00e9s dans la localit\u00e9 o\u00f9 l\u2019ouvrage propos\u00e9 doit \u00eatre construit ou dans les environs.<\/p>\n<p style=\"padding-left: 30px;\">(2.2) L\u2019avis vis\u00e9 au paragraphe (2.1) doit inviter les int\u00e9ress\u00e9s \u00e0 pr\u00e9senter par \u00e9crit au ministre leurs observations dans les trente jours suivant sa publication. \u00bb<\/p>\n<p><strong>Motion no 424 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, aux lignes 41 et 42, page 279, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab d\u00e9classer, dans des eaux navigables ou sur, sous, au-dessus ou \u00e0 \u00bb<\/p>\n<p><strong>Motion no 425 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, \u00e0 la ligne 26, page 281, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab bles ou sur, sous, au- \u00bb<\/p>\n<p><strong>Motion no 426 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, aux lignes 3 et 4, page 282, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab ou d\u00e9classer, dans des eaux navigables ou sur, sous, au-dessus ou \u00e0 \u00bb<\/p>\n<p><strong>Motion no 427 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, \u00e0 la ligne 34, page 282, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab des eaux navigables ou \u00bb<\/p>\n<p><strong>Motion no 428 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, \u00e0 la ligne 36, page 283, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab eaux navigables ou sur, \u00bb<\/p>\n<p><strong>Motion no 429 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, aux lignes 3 et 4, page 284, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab dans des eaux navigables ou sur, sous, au-dessus ou \u00e0 travers \u00bb<\/p>\n<p><strong>Motion no 430 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, aux lignes 30 et 31, page 284, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab cle dans des eaux navigables, autres que des eaux secondaires, est \u00bb<\/p>\n<p><strong>Motion no 431 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, aux lignes 13 et 14, page 285, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab potentiel, dans des eaux navigables, autres que des eaux secondaires, \u00bb<\/p>\n<p><strong>Motion no 432 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 318, soit modifi\u00e9 par substitution, aux lignes 35 et 36, page 285, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab obstacle dans des eaux navigables, autres que des eaux secondaires, ou \u00bb<\/p>\n<p><strong>Motion no 434 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 319, soit modifi\u00e9 par substitution, aux lignes 27 et 28, page 286, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab dans des eaux navigables, autres que des eaux secondaires, y \u00bb<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 436 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 320, soit modifi\u00e9 par substitution, \u00e0 la ligne 16, page 287, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab navigables, autres que \u00bb<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 438 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par suppression des lignes 24 \u00e0 32, page 288.<\/p>\n<p><strong>Motion no 439 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par substitution, \u00e0 la ligne 18, page 289, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab navigables \u2014 autres \u00bb<\/p>\n<p><strong>Motion no 440 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par substitution, \u00e0 la ligne 12, page 290, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab a) d\u00e9signant des ouvrages, autres que des ponts, des estacades, des barrages et des digues, comme ouvrages \u00bb<\/p>\n<p><strong>Motion no 441 \u2014 27 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par substitution, aux lignes 15 et 16, page 290, de ce qui suit : <\/strong><\/p>\n<p style=\"padding-left: 30px;\">\u00ab ou partie des eaux navigables \u00e0 l&#8217;exception des rivi\u00e8res du R\u00e9seau des rivi\u00e8res du patrimoine canadien et de celles qui constituent l&#8217;habitat d&#8217;une esp\u00e8ce sauvage en p\u00e9ril mentionn\u00e9e \u00e0 l&#8217;annexe 1 de la Loi sur les esp\u00e8ces en p\u00e9ril; \u00bb<\/p>\n<p><strong>Motion no 442 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par substitution, \u00e0 la ligne 22, page 290, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab navigables \u2014 autres \u00bb<\/p>\n<p><strong>Motion no 443 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 31, page 290, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (2.1) Avant de prendre un arr\u00eat\u00e9 en vertu de l&#8217;alin\u00e9a (2)a), le ministre \u00e9value les effets environnementaux potentiels de ces ouvrages.<\/p>\n<p style=\"padding-left: 30px;\">(2.2) Avant de prendre un arr\u00eat\u00e9 en vertu de l&#8217;alin\u00e9a (2)b), le ministre tient compte :<\/p>\n<p style=\"padding-left: 30px;\">a) de la valeur \u00e9cologique des eaux navigables;<\/p>\n<p style=\"padding-left: 30px;\">b) de l&#8217;utilit\u00e9 de ces eaux pour la p\u00eache et la chasse;<\/p>\n<p style=\"padding-left: 30px;\">c) de l&#8217;importance de ces eaux pour les peuples autochtones dans leurs usages traditionnels et autres.<\/p>\n<p style=\"padding-left: 30px;\">(2.3) Le ministre affiche le r\u00e9sum\u00e9 des \u00e9valuations faites au titre des paragraphes (2.1) et (2.2) sur le site Internet du minist\u00e8re des Transports. \u00bb<\/p>\n<p><strong>Motion no 444 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par substitution, aux lignes 38 \u00e0 42, page 290, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab 28.1 (1) Le ministre fait d\u00e9poser devant chaque chambre du Parlement tout projet d&#8217;arr\u00eat\u00e9 qu&#8217;il se propose de prendre en vertu des alin\u00e9as 28(2)a) ou b).<\/p>\n<p style=\"padding-left: 30px;\">(2) Tout comit\u00e9 comp\u00e9tent, d\u2019apr\u00e8s le r\u00e8glement de chacune des chambres, est automatiquement saisi du projet d&#8217;arr\u00eat\u00e9 et peut effectuer une enqu\u00eate ou tenir des audiences publiques \u00e0 cet \u00e9gard et faire rapport de ses conclusions \u00e0 la chambre en cause.<\/p>\n<p style=\"padding-left: 30px;\">(3) L&#8217;arr\u00eat\u00e9 peut \u00eatre pris :<\/p>\n<p style=\"padding-left: 30px;\">a) soit dans un d\u00e9lai de trente jours de s\u00e9ance suivant le second d\u00e9p\u00f4t devant l&#8217;une ou l&#8217;autre chambre;<\/p>\n<p style=\"padding-left: 30px;\">b) soit au moment, pour chaque chambre, o\u00f9, selon le cas :<\/p>\n<p style=\"padding-left: 30px;\">(i) le comit\u00e9 fait rapport,<\/p>\n<p style=\"padding-left: 30px;\">(ii) il d\u00e9cide de ne pas effectuer d\u2019enqu\u00eate ou de ne pas tenir d\u2019audiences publiques.<\/p>\n<p style=\"padding-left: 30px;\">(4) Pour l\u2019application du pr\u00e9sent article, \u00ab jour de s\u00e9ance \u00bb s\u2019entend d\u2019un jour o\u00f9 l\u2019une ou l\u2019autre chambre si\u00e8ge. \u00bb<\/p>\n<p><strong>Motion no 445 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par suppression des lignes 1 \u00e0 20, page 291.<\/p>\n<p><strong>Motion no 449 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 321, soit modifi\u00e9 par suppression des lignes 21 \u00e0 41, page 291.<\/p>\n<p><strong>Motion no 458 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 328, soit modifi\u00e9 par adjonction, apr\u00e8s la ligne 11, page 294, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab DROIT D\u2019ACTION<\/p>\n<p style=\"padding-left: 30px;\">39.01 Lorsqu&#8217;il est port\u00e9 atteinte au droit de navigation d&#8217;une personne \u00e0 l&#8217;\u00e9gard de toute eau navigable, ou qu&#8217;il sera vraisemblablement port\u00e9 atteinte \u00e0 ce droit, celle-ci peut demander r\u00e9paration pour nuisance publique sans le consentement du procureur g\u00e9n\u00e9ral et sans faire la preuve de dommages-int\u00e9r\u00eats particuliers. \u00bb<\/p>\n<p><strong>Motion no 461 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 331.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 463 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 332, soit modifi\u00e9 par suppression des lignes 21 \u00e0 37, page 301.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 483 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 352.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 485 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 354.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 488 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 357.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 490 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 358, soit modifi\u00e9 par substitution, \u00e0 la ligne 8, page 309, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab de demande de r\u00e9inspection, aupr\u00e8s du tribunal d&#8217;appel en mati\u00e8re de grains de la r\u00e9gion concern\u00e9e ou de l&#8217;ins- \u00bb<\/p>\n<p><strong>Motion no 492 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 358, soit modifi\u00e9 par substitution, \u00e0 la ligne 12, page 309, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab donn\u00e9 au tribunal d&#8217;appel en mati\u00e8re de grains de la r\u00e9gion concern\u00e9e ou \u00e0 l&#8217;inspecteur en chef des grains pour le \u00bb<\/p>\n<p><strong>Motion no 494 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 359, soit modifi\u00e9 par substitution, \u00e0 la ligne 17, page 309, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab 41. (1) Le tribunal d\u2019appel en mati\u00e8re de grains de la r\u00e9gion concern\u00e9e ou l&#8217;inspecteur en chef des grains pour \u00bb<\/p>\n<p><strong>Motion no 495 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 359, soit modifi\u00e9 par substitution, \u00e0 la ligne 28, page 309, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab (2) La d\u00e9cision du tribunal d\u2019appel en mati\u00e8re de grains de la r\u00e9gion concern\u00e9e ou de l&#8217;inspecteur en chef de \u00bb<\/p>\n<p><strong>Motion no 496 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 359, soit modifi\u00e9 par substitution, \u00e0 la ligne 34, page 309, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab paragraphe (1), pourvu qu&#8217;il soit d\u00e9montr\u00e9 que le d\u00e9l\u00e9gu\u00e9 n&#8217;a aucun int\u00e9r\u00eat direct ou indirect, financier ou autre, dans la d\u00e9cision sur l&#8217;appel. \u00bb<\/p>\n<p><strong>Motion no 500 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 362, soit modifi\u00e9 par substitution, aux lignes 13 et 14, page 310, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab titulaire de licence doit fournir une garantie, sous forme de cautionnement, afin de couvrir ses \u00bb<\/p>\n<p><strong>Motion no 502 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 363, soit modifi\u00e9 par substitution, \u00e0 la ligne 32, page 310, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab l&#8217;int\u00e9ress\u00e9 n&#8217;a pas fourni la garantie exig\u00e9e au \u00bb<\/p>\n<p><strong>Motion no 503 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 363, soit modifi\u00e9 par substitution, \u00e0 la ligne 39, page 310, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab n&#8217;a pas fourni la garantie exig\u00e9e au paragraphe \u00bb<\/p>\n<p><strong>Motion no 505 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 364, soit modifi\u00e9 par substitution, \u00e0 la ligne 2, page 311, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab que la garantie fournie en application de la \u00bb<\/p>\n<p><strong>Motion no 506 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 364, soit modifi\u00e9 par substitution, \u00e0 la ligne 13, page 311, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab fournie par le titulaire de licence peut \u00eatre \u00bb<\/p>\n<p><strong>Motion no 512 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 369, soit modifi\u00e9 par substitution, \u00e0 la ligne 36, page 313, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab installation terminale agr\u00e9\u00e9e fait proc\u00e9der \u00e0 la pes\u00e9e officielle du grain re\u00e7u \u00e0 \u00bb<\/p>\n<p><strong>Motion no 513 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 369, soit modifi\u00e9 par substitution, \u00e0 la ligne 1, page 314, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab Commission et dont il a \u00e9t\u00e9 d\u00e9montr\u00e9 qu&#8217;il n&#8217;a aucun int\u00e9r\u00eat direct ou indirect, financier ou autre, dans le grain, et qu&#8217;il choisit, dans le cas o\u00f9 la \u00bb<\/p>\n<p><strong>Motion no 514 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 369, soit modifi\u00e9 par substitution, \u00e0 la ligne 25, page 314, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab la Commission et dont il a \u00e9t\u00e9 d\u00e9montr\u00e9 qu&#8217;il n&#8217;a aucun int\u00e9r\u00eat direct ou indirect, financier ou autre, dans le grain, et qu&#8217;il choisit, dans le cas o\u00f9 la \u00bb<\/p>\n<p><strong>Motion no 515 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 369, soit modifi\u00e9<\/p>\n<p style=\"padding-left: 30px;\">a) par substitution, \u00e0 la ligne 37, page 314, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab autres modalit\u00e9s r\u00e9glementaires, demander au tribunal d&#8217;appel de la r\u00e9gion concern\u00e9e ou \u00e0 \u00bb<\/p>\n<p style=\"padding-left: 30px;\">b) par substitution, \u00e0 la ligne 40, page 314, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab tant transmet \u00e0 l&#8217;un ou l&#8217;autre de ceux-ci dans le d\u00e9lai \u00bb<\/p>\n<p><strong>Motion no 516 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 369, soit modifi\u00e9 par substitution, \u00e0 la ligne 24, page 315, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab article, pourvu qu&#8217;il soit d\u00e9montr\u00e9 que le d\u00e9l\u00e9gu\u00e9 n&#8217;a aucun int\u00e9r\u00eat direct ou indirect, financier ou autre, dans la d\u00e9cision. \u00bb<\/p>\n<p><strong>Motion no 517 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 369, soit modifi\u00e9<\/p>\n<p style=\"padding-left: 30px;\">a) par substitution, aux lignes 17 et 18, page 316, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab 70.2 (1) L&#8217;exploitant d&#8217;une installa- \u00bb<\/p>\n<p style=\"padding-left: 30px;\">b) par substitution, aux lignes 20 et 21, page 316, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab grain re\u00e7u \u00e0 l&#8217;installation par un tiers ou fait \u00bb<\/p>\n<p><strong>Motion no 518 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45, \u00e0 l&#8217;article 369, soit modifi\u00e9 par substitution, \u00e0 la ligne 26, page 316, de ce qui suit :<\/p>\n<p style=\"padding-left: 30px;\">\u00ab choisi par l&#8217;exploitant. Seul peut \u00eatre autoris\u00e9 le tiers dont il a \u00e9t\u00e9 d\u00e9montr\u00e9 qu&#8217;il n&#8217;a aucun int\u00e9r\u00eat direct ou indirect, financier ou autre, dans le r\u00e9sultat de la pes\u00e9e ou de l&#8217;inspection. \u00bb<\/p>\n<p><strong>Motion no 525 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 376.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 526 \u2014<\/strong> 26 novembre 2012 \u2014 Mme Nash (Parkdale\u2014High Park) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;article 377.<\/p>\n<p style=\"padding-left: 30px;\">Conform\u00e9ment \u00e0 l&#8217;article 76.1(2) du R\u00e8glement, avis aussi re\u00e7u de :<\/p>\n<p style=\"padding-left: 30px;\">M. Caron (Rimouski-Neigette\u2014T\u00e9miscouata\u2014Les Basques), M. Marston (Hamilton-Est\u2014Stoney Creek), M. Mai (Brossard\u2014La Prairie), Mme May (Saanich\u2014Gulf Islands),<\/p>\n<p style=\"padding-left: 30px;\">M. Lamoureux (Winnipeg-Nord), M. Garneau (Westmount\u2014Ville-Marie) et M. Brison (Kings\u2014Hants) \u201426 novembre 2012<\/p>\n<p><strong>Motion no 662 \u2014<\/strong> 26 novembre 2012 \u2014 Mme May (Saanich\u2014Gulf Islands) \u2014 Que le projet de loi C-45 soit modifi\u00e9 par suppression de l&#8217;annexe 2.<\/p>","protected":false},"excerpt":{"rendered":"<p>Projet de loi C-45 : Loi no 2 portant ex\u00e9cution de certaines dispositions du budget d\u00e9pos\u00e9 au Parlement le 29 mars 2012 et mettant en oeuvre d&#8217;autres mesures&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[1],"tags":[1526,472],"class_list":["post-7713","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-bill-c-45","tag-budget"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les amendements au projet de loi C-45 | Elizabeth May<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les amendements au projet de loi C-45 | Elizabeth May\" \/>\n<meta property=\"og:description\" content=\"Projet de loi C-45 : Loi no 2 portant ex\u00e9cution de certaines dispositions du budget d\u00e9pos\u00e9 au Parlement le 29 mars 2012 et mettant en oeuvre d&#8217;autres mesures&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/\" \/>\n<meta property=\"og:site_name\" content=\"Elizabeth May\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElizabethMayMP\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-28T22:02:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-11-28T22:56:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Craig Cantin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:site\" content=\"@elizabethmay\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Craig Cantin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"47 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/amendments-to-bill-c-45\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/amendments-to-bill-c-45\\\/\"},\"author\":{\"name\":\"Craig Cantin\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\"},\"headline\":\"Les amendements au projet de loi C-45\",\"datePublished\":\"2012-11-28T22:02:22+00:00\",\"dateModified\":\"2012-11-28T22:56:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/amendments-to-bill-c-45\\\/\"},\"wordCount\":9514,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#organization\"},\"keywords\":[\"Bill C-45\",\"Le budget\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/amendments-to-bill-c-45\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/amendments-to-bill-c-45\\\/\",\"name\":\"Amendments to Bill C-45Les amendements au projet de loi C-45 | Elizabeth May\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\"},\"datePublished\":\"2012-11-28T22:02:22+00:00\",\"dateModified\":\"2012-11-28T22:56:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/amendments-to-bill-c-45\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/amendments-to-bill-c-45\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/amendments-to-bill-c-45\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amendments to Bill C-45\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"name\":\"Elizabeth May\",\"description\":\"MP for Saanich and Gulf Islands\",\"publisher\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#organization\",\"name\":\"Elizabeth May MP\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"contentUrl\":\"https:\\\/\\\/elizabethmaymp.ca\\\/wp-content\\\/uploads\\\/elizabethmay-button.png\",\"width\":1501,\"height\":1501,\"caption\":\"Elizabeth May MP\"},\"image\":{\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElizabethMayMP\",\"https:\\\/\\\/x.com\\\/elizabethmay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elizabethmaymp.ca\\\/#\\\/schema\\\/person\\\/d3f03a762a6bc9b615b1cc303ebf0c1f\",\"name\":\"Craig Cantin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g\",\"caption\":\"Craig Cantin\"},\"url\":\"https:\\\/\\\/elizabethmaymp.ca\\\/fr\\\/author\\\/craig-c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les amendements au projet de loi C-45 | Elizabeth May","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/","og_locale":"en_US","og_type":"article","og_title":"Les amendements au projet de loi C-45 | Elizabeth May","og_description":"Projet de loi C-45 : Loi no 2 portant ex\u00e9cution de certaines dispositions du budget d\u00e9pos\u00e9 au Parlement le 29 mars 2012 et mettant en oeuvre d&#8217;autres mesures&hellip;","og_url":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/","og_site_name":"Elizabeth May","article_publisher":"https:\/\/www.facebook.com\/ElizabethMayMP","article_published_time":"2012-11-28T22:02:22+00:00","article_modified_time":"2012-11-28T22:56:43+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/cropped-elizabethmay-button.png","type":"image\/png"}],"author":"Craig Cantin","twitter_card":"summary_large_image","twitter_creator":"@elizabethmay","twitter_site":"@elizabethmay","twitter_misc":{"Written by":"Craig Cantin","Est. reading time":"47 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/#article","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/"},"author":{"name":"Craig Cantin","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f"},"headline":"Les amendements au projet de loi C-45","datePublished":"2012-11-28T22:02:22+00:00","dateModified":"2012-11-28T22:56:43+00:00","mainEntityOfPage":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/"},"wordCount":9514,"commentCount":0,"publisher":{"@id":"https:\/\/elizabethmaymp.ca\/#organization"},"keywords":["Bill C-45","Le budget"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/","url":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/","name":"Amendments to Bill C-45Les amendements au projet de loi C-45 | Elizabeth May","isPartOf":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#website"},"datePublished":"2012-11-28T22:02:22+00:00","dateModified":"2012-11-28T22:56:43+00:00","breadcrumb":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elizabethmaymp.ca\/fr\/amendments-to-bill-c-45\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elizabethmaymp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Amendments to Bill C-45"}]},{"@type":"WebSite","@id":"https:\/\/elizabethmaymp.ca\/fr\/#website","url":"https:\/\/elizabethmaymp.ca\/fr\/","name":"Elizabeth May","description":"MP for Saanich and Gulf Islands","publisher":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elizabethmaymp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elizabethmaymp.ca\/fr\/#organization","name":"Elizabeth May MP","url":"https:\/\/elizabethmaymp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","contentUrl":"https:\/\/elizabethmaymp.ca\/wp-content\/uploads\/elizabethmay-button.png","width":1501,"height":1501,"caption":"Elizabeth May MP"},"image":{"@id":"https:\/\/elizabethmaymp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElizabethMayMP","https:\/\/x.com\/elizabethmay"]},{"@type":"Person","@id":"https:\/\/elizabethmaymp.ca\/#\/schema\/person\/d3f03a762a6bc9b615b1cc303ebf0c1f","name":"Craig Cantin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c95358098caf4f50815f5fc942d6d14142d8b46ece2b18c21ac1fb7d38545a4?s=96&d=mm&r=g","caption":"Craig Cantin"},"url":"https:\/\/elizabethmaymp.ca\/fr\/author\/craig-c\/"}]}},"_links":{"self":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/7713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/comments?post=7713"}],"version-history":[{"count":7,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/7713\/revisions"}],"predecessor-version":[{"id":7715,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/posts\/7713\/revisions\/7715"}],"wp:attachment":[{"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/media?parent=7713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/categories?post=7713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elizabethmaymp.ca\/fr\/wp-json\/wp\/v2\/tags?post=7713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}